{"id":14868,"date":"2013-09-05T19:42:42","date_gmt":"2013-09-05T18:42:42","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=14868"},"modified":"2013-09-05T19:42:42","modified_gmt":"2013-09-05T18:42:42","slug":"en-realidad-es-la-realidad","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/en-realidad-es-la-realidad\/","title":{"rendered":"En realidad, es la Realidad"},"content":{"rendered":"<p style=\"text-align: justify;\">Estoy convencido de que una de las causas de la crisis que nos azota es la cantidad de tiempo, esfuerzo y dinero que invertimos en hablar, estudiar y discutir sobre ciertas cretinadas. Como la de la depresi\u00f3n postvacacional, sin ir m\u00e1s lejos.<\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/09\/Estr\u00e9s-Posvacacional.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-14869\" alt=\"Estr\u00e9s Posvacacional\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/09\/Estr\u00e9s-Posvacacional-300x229.jpg\" width=\"300\" height=\"229\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/09\/Estr\u00e9s-Posvacacional-300x229.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/09\/Estr\u00e9s-Posvacacional.jpg 550w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Hoy, tener trabajo, es un lujo y un privilegio, por lo que decir en voz alta que uno siente desaz\u00f3n por volver al trabajo puede resultar molesto, inadecuado y hasta ofensivo. Eso es cierto. Pero no lo es menos que odiamos que se terminen las vacaciones y por eso, cuando llegan estas fechas, lo normal es ver caras largas y sentir un cierto tufo a mal humor en la gente que nos rodea.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Dig\u00e1moslo claro: si has disfrutado de unas buenas vacaciones, al volver, estar\u00e1s de mala leche. Y punto. Ll\u00e1malo depresi\u00f3n, s\u00edndrome o estr\u00e9s. Te va a dar igual. Y si no tienes los s\u00edntomas es porque tus vacaciones habr\u00e1n sido decepcionantes, m\u00e1s all\u00e1 de haber hecho caso a los consejos de los expertos del ramo.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Otro t\u00f3pico: venir descansado de las vacaciones. \u00bfC\u00f3mo? \u00bfDescansado? \u00a1Descansado de qu\u00e9! Salvo que tu trabajo diario implique un desgaste f\u00edsico importante, venir descansado de las vacaciones es una contradicci\u00f3n. Con la vida tan sedentaria que llevamos la mayor\u00eda, unas buenas vacaciones deber\u00edan implicar acci\u00f3n, movimiento, actividad f\u00edsica, trasiego y, por tanto, cansancio. Porque un cuerpo fundido es uno de los mejores medios para conseguir una mente \u00e1gil, r\u00e1pida, atenta y despejada.<\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/09\/Estr\u00e9s-Postvacacional-desconexi\u00f3n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-14870\" alt=\"Estr\u00e9s Postvacacional desconexi\u00f3n\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/09\/Estr\u00e9s-Postvacacional-desconexi\u00f3n-300x300.jpg\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/09\/Estr\u00e9s-Postvacacional-desconexi\u00f3n-300x300.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/09\/Estr\u00e9s-Postvacacional-desconexi\u00f3n-150x150.jpg 150w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/09\/Estr\u00e9s-Postvacacional-desconexi\u00f3n.jpg 403w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Con lo que llegamos a la c\u00e9lebre desconexi\u00f3n. \u00bfHay que desconectar, en vacaciones? Pues depende. Si desconectar es sin\u00f3nimo de cambiar los h\u00e1bitos y las rutinas, de alejarnos de los quebraderos de cabeza diarios; indudablemente s\u00ed. Ahora bien, si por desconectar entendemos dimitir de nosotros mismos y cesar en las funciones cerebrales m\u00ednimas; no tanto. No comprendo a la gente que, en vacaciones, rebaja y relaja hasta lo indecible sus est\u00e1ndares de decoro y dignidad.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\u00bfPor qu\u00e9 sirve el verano como coartada para hacer cosas que, en cualquier otra \u00e9poca del a\u00f1o, ni se nos pasar\u00edan por la cabeza? Concedamos que el calor nos legitima para vestir bermudas y sandalias. Pero de ah\u00ed a hacer determinadas sandeces deber\u00eda mediar un abismo. Sobre esto, curiosamente, no he le\u00eddo estudio alguno\u2026<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Es un hecho. Agosto termina y llega septiembre. Vuelven los problemas, las necesidades, las angustias, las prisas y las presiones. La verdad es que nunca se fueron, pero el calor parec\u00eda mantenerlas aplacadas, distantes y alejadas. Ya no hay excusas. Los quioscos se han llenado de coleccionables, ha comenzado el Festival de Cine de Venecia, llega el Eurob\u00e1sket y de las vacaciones solo queda un \u00e1lbum de fotos en el Facebook.<\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/09\/Estr\u00e9s-Postvacacional.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-14871\" alt=\"Estr\u00e9s Postvacacional\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/09\/Estr\u00e9s-Postvacacional-300x208.jpg\" width=\"300\" height=\"208\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/09\/Estr\u00e9s-Postvacacional-300x208.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/09\/Estr\u00e9s-Postvacacional.jpg 490w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Eso s\u00ed. \u00a1Qu\u00e9 no nos enga\u00f1en! No es ning\u00fan s\u00edndrome postvacacional lo que nos angustia, nos quita el sue\u00f1o y nos provoca ansiedad. Es, por desgracia, la realidad misma, la que nos da miedo. Mucho miedo.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Jes\u00fas Lens<\/p>\n<p style=\"text-align: justify;\">En Twitter: @Jesus_Lens<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estoy convencido de que una de las causas de la crisis que nos azota es la cantidad de tiempo, esfuerzo y dinero que invertimos en hablar, estudiar y discutir sobre ciertas cretinadas. Como la de la depresi\u00f3n postvacacional, sin ir m\u00e1s lejos. \u00a0 Hoy, tener trabajo, es un lujo y un privilegio, por lo que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[9038,9037,9040,9039,9036,9035,9041,1538],"class_list":["post-14868","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-depresion-postvacacional","tag-depresion-posvacacional","tag-desconectar","tag-desconexion","tag-estres-postvacacional","tag-estres-posvacacional","tag-volver-de-vacaciones","tag-vuelta-de-vacaciones"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/14868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=14868"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/14868\/revisions"}],"predecessor-version":[{"id":14872,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/14868\/revisions\/14872"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=14868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=14868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=14868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}