{"id":14773,"date":"2013-08-28T11:31:59","date_gmt":"2013-08-28T10:31:59","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=14773"},"modified":"2013-08-28T11:31:59","modified_gmt":"2013-08-28T10:31:59","slug":"world-war-z","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/world-war-z\/","title":{"rendered":"World War Z"},"content":{"rendered":"<p style=\"text-align: justify;\">Como bien sab\u00e9is, yo soy muy de zombis, del apocalipsis y del fin del mundo. De hecho, lo avanzaba en esta entrada, nada m\u00e1s ver la \u00faltima pel\u00edcula de Brad Pitt: <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/y-si-ya-ha-comenzado-el-apocalipsis\/\" target=\"_blank\">\u00bfY si hubiera comenzado ya el apocalipsis?<\/a><\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/08\/WWZ.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-14774\" alt=\"WWZ\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/08\/WWZ-300x187.jpg\" width=\"300\" height=\"187\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/08\/WWZ-300x187.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/08\/WWZ-1024x640.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Desde <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/antirresurreccion\/\" target=\"_blank\">los libros de Biedma<\/a>, pasando por <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/the-walking-dead\/\" target=\"_blank\">\u201cThe Walking Dead\u201d<\/a>, <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/la-alhambra-ultimo-balurate-antizombis\/\" target=\"_blank\">Los Caminantes de Sisi<\/a>, el <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/cenital\/\" target=\"_blank\">Cenital<\/a> de Bueso, <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/la-zona\/\" target=\"_blank\">La Zona<\/a> de Aguilera &amp; Negrete e, incluso, a trav\u00e9s de relatos como el <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/zombilizacion\/\" target=\"_blank\">Be Zombie My Friend<\/a>; este tema siempre me ha parecido apasionante. \u00bfQu\u00e9 le hago yo, si me pirro por la carne descompuesta, la masa informe, las v\u00edsceras podridas, las heridas purulentas y las dentelladas a traici\u00f3n? Cada uno tiene sus vicios, m\u00e1s o menos (in)confesables\u2026<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Era obligatorio, pues, ir al cine a ver una pel\u00edcula de zombies de gran presupuesto, interpretada por todo un gal\u00e1ctico como Brad Pitt. Ya daba por supuesto que las dosis de sangre y de violencia que saltar\u00edan de la pantalla a la platea ser\u00edan reducidas y, bajo esa premisa, me plant\u00e9 en el Cinema 2000, una t\u00f3rrida tarde de agosto, a precio felizmente reducido&#8230;<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Me gust\u00f3 el arranque: un poco de informaci\u00f3n, unos brochazos de actualidad sobre los primeros indicios de la enfermedad y, de inmediato, la explosi\u00f3n de violencia. \u00a1Hasta me gust\u00f3 la obligatoria secuencia de coches-a-toda-mecha que debe tener toda pel\u00edcula de acci\u00f3n!<\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/08\/World-War-Z-zombi.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-14775\" alt=\"World War Z zombi\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/08\/World-War-Z-zombi-300x205.jpeg\" width=\"300\" height=\"205\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/08\/World-War-Z-zombi-300x205.jpeg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/08\/World-War-Z-zombi.jpeg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Llega, sobre la marcha, la primera pelea cuerpo a cuerpo. Y ah\u00ed ya s\u00ed que me mareo. Y sin gafas 3D. Los planos son tan cortos, r\u00e1pidos y veloces que mi retina no da abasto. Creo que, por mor de las series y su estilo m\u00e1s pausado, empiezo a estar desfasado y sobrepasado, cinematogr\u00e1ficamente hablando. Acostumbrado a lo deliciosamente lento que transcurre todo en \u201cThe walking dead\u201d, me siento sobrepasado por la velocidad y la acumulaci\u00f3n de segmentos que conforman \u201cWorld War Z\u201d.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">La recogida del helic\u00f3ptero, la llegada al barco, el viaje a Corea, el episodio de Jerusal\u00e9n, la escapada a la India y, por fin, Escocia. \u00a1En apenas dos horas de pel\u00edcula!<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Dejando al margen las inequ\u00edvocas connotaciones que tiene el surrealista episodio de Jerusal\u00e9n; disfrut\u00e9 con los vaivenes de Pitt en su enloquecida vuelta a un mundo m\u00e1s enloquecido a\u00fan; me gust\u00f3 la decisiva intervenci\u00f3n del cient\u00edfico al que acompa\u00f1a en su peligrosa misi\u00f3n y me dej\u00e9 envolver por la tensi\u00f3n del \u00faltimo segmento de la pel\u00edcula, mirando el reloj y pensando que se acababan las dos horas de metraje y la historia segu\u00eda inconclusa.<\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/08\/World-War-Z-muro.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-14776\" alt=\"World War Z muro\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/08\/World-War-Z-muro-300x169.jpeg\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/08\/World-War-Z-muro-300x169.jpeg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/08\/World-War-Z-muro-1024x579.jpeg 1024w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/08\/World-War-Z-muro.jpeg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">No me parece \u201cWorld War Z\u201d una obra maestra memorable ni creo que pase a los anales del cine de terror, pero se deja ver y nos muestra algo que, pens\u00e1bamos, era radicalmente imposible: \u00a1Brad Pitt es humano, est\u00e1 envejeciendo y puede llegar a parecer feo en una pantalla, con el pelo churretoso y las bolsas bajo los ojos!<\/p>\n<p style=\"text-align: justify;\">\n<figure id=\"attachment_14777\" aria-describedby=\"caption-attachment-14777\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/08\/World-War-Z-pitt.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-14777\" alt=\"Espejito, espejito...\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/08\/World-War-Z-pitt-300x190.jpeg\" width=\"300\" height=\"190\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/08\/World-War-Z-pitt-300x190.jpeg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/08\/World-War-Z-pitt.jpeg 630w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-14777\" class=\"wp-caption-text\">Espejito, espejito&#8230;<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Eso s\u00ed. Creo que WWZ, en televisi\u00f3n, en ordenador o en iPad; no se aguantar\u00eda.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Y es que, como venimos sosteniendo, \u00a1no es lo mismo ver una pel\u00edcula que ir al cine!<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">En este caso, sin el escaparate de la pantalla gigante y de la conjunci\u00f3n de los espectadores conteniendo la respiraci\u00f3n; la experiencia zombie se diluir\u00e1 como un terr\u00f3n de az\u00facar en el caf\u00e9 caliente\u2026<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">En Twitter: @Jesus_Lens<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como bien sab\u00e9is, yo soy muy de zombis, del apocalipsis y del fin del mundo. De hecho, lo avanzaba en esta entrada, nada m\u00e1s ver la \u00faltima pel\u00edcula de Brad Pitt: \u00bfY si hubiera comenzado ya el apocalipsis? \u00a0 Desde los libros de Biedma, pasando por \u201cThe Walking Dead\u201d, Los Caminantes de Sisi, el Cenital [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[1844,10,5375,66,8978,8976,8977,6163,3381],"class_list":["post-14773","post","type-post","status-publish","format-standard","hentry","category-cine","tag-brad-pitt","tag-cine","tag-ir-al-cine","tag-peliculas","tag-peliculas-de-zombies","tag-world-war-z","tag-wwz","tag-zombi","tag-zombies"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/14773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=14773"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/14773\/revisions"}],"predecessor-version":[{"id":14778,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/14773\/revisions\/14778"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=14773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=14773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=14773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}