{"id":14602,"date":"2013-07-17T13:28:14","date_gmt":"2013-07-17T12:28:14","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=14602"},"modified":"2013-07-17T13:28:14","modified_gmt":"2013-07-17T12:28:14","slug":"la-posada-de-procusto","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/la-posada-de-procusto\/","title":{"rendered":"La Posada de Procusto"},"content":{"rendered":"<p>Me ocurri\u00f3 hace ya muchos a\u00f1os, en uno de mis primeros viajes por la zona de \u00c1tica. Entones yo era joven y viajaba a mi aire, con el macuto a cuestas (el revolucionario invento de la maleta con ruedas todav\u00eda no se le hab\u00eda ocurrido a nadie).<\/p>\n<p>Se me hizo tarde. Ca\u00eda la noche. Estaba en mitad de ning\u00fan sitio, en un camino solitario. Me hab\u00eda hecho el cuerpo a pasar la noche en mi saco de dormir, durmiendo bajo un \u00e1rbol, cuando la suerte hizo que una posada apareciera al dar una curva.<\/p>\n<p>La mala suerte, quiero decir.<\/p>\n<p>Porque, en realidad, no abrigaba intenci\u00f3n de entrar en la posada, pero su due\u00f1o, un tal Procusto, sonriendo abiertamente, me invit\u00f3 a compartir con \u00e9l aunque fuera un vaso de vino y a hablar un rato de mis aventuras viajeras.<\/p>\n<p>Cuando traspas\u00e9 las puertas de la fonda, me sorprend\u00ed al encontrarla vac\u00eda. D\u00e1ndome pena el posadero -a la vista estaba que pasaba una mala racha- no tard\u00e9 en ponerme de acuerdo con \u00e9l en el precio de la habitaci\u00f3n y, tras tomar un guiso de carne, algo correosa pero ciertamente sabrosa, sub\u00ed a mi habitaci\u00f3n.<\/p>\n<p>Reconozco que, ante la insistencia de Procusto en que me apurara el plato, aprovech\u00e9 que fue en busca del postre para darle la mitad a un enorme perrazo negro que andaba por la estancia, moviendo la cola y salivando abundantemente. Y es que a mediod\u00eda me hab\u00eda cruzado con un amable pastor y hab\u00edamos estado compartiendo buen vino y mejores y abundantes viandas, quedando ah\u00edto. Adem\u00e1s, estaba demasiado cansado, tras haber caminado todo el d\u00eda, por lo que me ase\u00e9 r\u00e1pidamente y me acost\u00e9, no tardando en quedarme dormido.<\/p>\n<p>Fue un ronquido lo que termin\u00f3 de despertarme. Un ronquido propio, quiero decir. Y es que yo solo ronco cuando duermo bocarriba. Pero nunca duermo bocarriba. De hecho, recordaba perfectamente haberme puesto de costado al acostarme: como ocurr\u00eda habitualmente en mis viajes, la cama me quedaba peque\u00f1a as\u00ed que, de lado, sol\u00eda encoger las rodillas para ponerme en posici\u00f3n fetal, la que mejor me permit\u00eda descansar.<\/p>\n<p>El caso es que, antes de escuchar el ronquido, cre\u00ed notar que alguien me mov\u00eda y zarandeaba, pero mi mente estaba pesada y espesa y lo achaqu\u00e9 a un sue\u00f1o demasiado v\u00edvido. Pero no. No era un sue\u00f1o. Al despertar comprob\u00e9 que, efectivamente, estaba bocarriba. Y que ten\u00eda las manos atadas al cabecero de la cama, percat\u00e1ndome con espanto y horror de que el posadero trataba de hacer lo mismo con mis pies.<\/p>\n<p>Aunque torpemente, consegu\u00ed dar una certera patada en la cabeza a Procusto, con la buena fortuna de hacerle perder el equilibro y de que cayera hacia atr\u00e1s, precipit\u00e1ndose al vac\u00edo a trav\u00e9s de la ventana de mi habitaci\u00f3n. Qued\u00f3 desnucado sobre el patio de su posada, con el cuerpo desmadejado, como si fuera un mu\u00f1eco de trapo, con un hilillo de sangre goteando de la nariz y desliz\u00e1ndose hasta el suelo.<\/p>\n<p>Despu\u00e9s del amanecer, mis gritos atrajeron a un viajero. Por fin. Desconfiado, el hombre no me liber\u00f3 y se limit\u00f3 a llamar a la gendarmer\u00eda. No se lo reprocho, aunque me viera obligado a pasar otro par de horas atado a la cama, esperando a que los agentes terminaran de desayunar.<\/p>\n<p>Un desayuno que poco les aguant\u00f3 en las tripas, la verdad sea dicha: en cuanto comprobaron que Procusto, adem\u00e1s de las esposas con las que hab\u00eda tratado de inmovilizarme, hab\u00eda subido a mi cuarto un hacha y una sierra, se dieron cuenta de que all\u00ed pasaba algo ciertamente extra\u00f1o. Y lo comprobaron en cuanto excavaron la tierra revuelta que hab\u00eda en una zona del jard\u00edn y comenzaron a aparecer decenas de piernas cortadas, en diferente grado de descomposici\u00f3n.<\/p>\n<p>Pero lo peor fue cuando, excavando en un huerto cercano, la polic\u00eda encontr\u00f3 m\u00e1s restos humanos. En este caso, eran cuerpos enteros. Los cuerpos de personas estirazadas hasta quedar completamente descoyuntadas.<\/p>\n<p>Los forenses no tardaron en hallar el extra\u00f1o patr\u00f3n por el que se reg\u00edan las pulsiones homicidas de Procusto: el tama\u00f1o de la cama. Todo aquel m\u00e1s peque\u00f1o que la \u00fanica cama que en realidad hab\u00eda en la posada, era estirado sin piedad, hasta que su cuerpo encajaba perfectamente en sus dimensiones. De la misma manera, a los que eran m\u00e1s altos, como ocurr\u00eda en mi caso, Procusto les cortaba las extremidades inferiores, a la altura que les permitiera dormir el sue\u00f1o de los justos\u2026 dentro de los l\u00edmites marcados por la siniestra cama.<\/p>\n<p>Lo m\u00e1s curioso es que, hechas las comprobaciones pertinentes, ni el mismo Procusto encajaba en su propio lecho.<\/p>\n<p>As\u00ed, no es de extra\u00f1ar que, una vez enterrado, alguien profanara el cad\u00e1ver de Procusto y lo dejara expuesto sobre su tumba, con los pies seccionados y la cabeza separada del tronco. Un alguien que, arrepentido de haber confiado en un pu\u00f1ado de buenas palabras y en una sonrisa piadosa, sigui\u00f3 su camino dispuesto a no tropezar dos veces con la misma piedra, acompa\u00f1ado por un descomunal perro que arrastraba penosamente su negra figura, como si estuviera bajo los efectos de una interminable resaca.<\/p>\n<p>En Twitter podemos seguirnos las andanzas: @Jesus_Lens<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Me ocurri\u00f3 hace ya muchos a\u00f1os, en uno de mis primeros viajes por la zona de \u00c1tica. Entones yo era joven y viajaba a mi aire, con el macuto a cuestas (el revolucionario invento de la maleta con ruedas todav\u00eda no se le hab\u00eda ocurrido a nadie). Se me hizo tarde. Ca\u00eda la noche. Estaba [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[31],"tags":[930,8826,8825,8824,8823,31],"class_list":["post-14602","post","type-post","status-publish","format-standard","hentry","category-relatos","tag-cuentos","tag-mentes-cerradas","tag-mentes-cuadriculadas","tag-posada-procusto","tag-procusto","tag-relatos"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/14602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=14602"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/14602\/revisions"}],"predecessor-version":[{"id":14603,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/14602\/revisions\/14603"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=14602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=14602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=14602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}