{"id":14541,"date":"2013-07-08T10:11:40","date_gmt":"2013-07-08T09:11:40","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=14541"},"modified":"2013-07-08T10:11:40","modified_gmt":"2013-07-08T09:11:40","slug":"alaya","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/alaya\/","title":{"rendered":"Alaya"},"content":{"rendered":"<p style=\"text-align: justify;\">\u00bfQu\u00e9 ser\u00eda de la lectura de la prensa sin la foto diaria del pase\u00edllo de la jueza Alaya, arrastrando su maleta, a la entrada y a la salida de su juzgado sevillano? El otro d\u00eda lo comentaba con un compa\u00f1ero de trabajo y, sin embargo, amigo: \u00bfcu\u00e1nto hay de postureo en la actitud de do\u00f1a Mercedes?<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/07\/Alaya.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-14542\" alt=\"Alaya\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/07\/Alaya.jpg\" width=\"607\" height=\"532\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Item m\u00e1s: \u00bfest\u00e1 cobrando las horas extra que debe pasar con los papeles de los ERE en casa o deber\u00eda irrumpir la Inspecci\u00f3n de Trabajo, una tarde cualquiera, en su hogar, a ver lo que se cuece all\u00e1 dentro?\u00a0Sin entrar en la que se\u00a0armar\u00eda si, aprovechando estos calores, a alg\u00fan caco despistado y poco informado le diera por pegar un tir\u00f3n a la trolley de la jueza, pensando que es una turista cualquiera&#8230;<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">El guante est\u00e1 lanzado: \u00bfpostureo o denodada\u00a0e infatigable trabajadora?<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">En Twitter tambi\u00e9n se admiten respuestas: @Jesus_Lens\u00a0\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 ser\u00eda de la lectura de la prensa sin la foto diaria del pase\u00edllo de la jueza Alaya, arrastrando su maleta, a la entrada y a la salida de su juzgado sevillano? El otro d\u00eda lo comentaba con un compa\u00f1ero de trabajo y, sin embargo, amigo: \u00bfcu\u00e1nto hay de postureo en la actitud de do\u00f1a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[32,7],"tags":[8773,32,7,8774,8777,8775,8776],"class_list":["post-14541","post","type-post","status-publish","format-standard","hentry","category-humor","category-imagenes","tag-ere","tag-humor","tag-imagenes","tag-jueza-alaya","tag-jueza-eres","tag-postureo-alaya","tag-postureo-jueza-alaya"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/14541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=14541"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/14541\/revisions"}],"predecessor-version":[{"id":14543,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/14541\/revisions\/14543"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=14541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=14541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=14541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}