{"id":144,"date":"2008-04-02T08:45:00","date_gmt":"2008-04-02T07:45:00","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=144"},"modified":"2008-04-02T08:45:00","modified_gmt":"2008-04-02T07:45:00","slug":"los-bikinis-como-agentes-democratizadores","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/los-bikinis-como-agentes-democratizadores\/","title":{"rendered":"LOS BIKINIS COMO AGENTES DEMOCRATIZADORES"},"content":{"rendered":"<div align=\"justify\"><em><span style=\"font-family:times new roman;\"><\/span><\/em> <\/div>\n<div align=\"justify\"><em><span style=\"font-family:times new roman;\">Recuperamos unas notas, escritas hace unos meses, que ten\u00edamos por ah\u00ed sepultadas. Ahora que llega el calor, hablemos de bikinis.<br \/><\/span><\/em><br \/>Una vez escrib\u00ed que, en nuestro proceso de consolidaci\u00f3n democr\u00e1tica, las turistas suecas semidesnudas tuvieron mucha m\u00e1s importancia que las haza\u00f1as de tanto y tanto jovenzuelo, corriendo delante de los grises y reuni\u00e9ndose en interminables asambleas en que se discut\u00eda sobre el ser y la nada. <\/div>\n<div align=\"justify\"> <\/div>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5184551511631366594\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp2.blogger.com\/_r6VY1mvj3jk\/R_M6IYKAicI\/AAAAAAAABIw\/lvMjTqt9EvI\/s400\/_7.jpg\" border=\"0\" \/> <\/p>\n<p align=\"justify\">Reconociendo un cierto tono provocativo en la aseveraci\u00f3n, estaba aut\u00e9nticamente convencido sobre el fondo de la misma. La normalidad democr\u00e1tica significa aceptar a los otros como son, perder el miedo al cuerpo y admitir al que es diferente. La normalidad democr\u00e1tica supone ser de izquierdas y hablar con los de derechas. Y viceversa. Y, en todo ello, el turismo jug\u00f3 un papel determinante en una Espa\u00f1a mojigata, pacata y absolutamente conservadora.<\/p>\n<p>Hace unos meses, Alfonso Guerra \u201cofreci\u00f3 una lectura desmitificadora de aquel tiempo (la transici\u00f3n) del que fue protagonista, sin que ello resultara contradictorio con sostener que \u00abfue una gesta de la que sentirse orgulloso\u00bb. <\/p>\n<p align=\"justify\"> <\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5184551507336399282\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp1.blogger.com\/_r6VY1mvj3jk\/R_M6IIKAibI\/AAAAAAAABIo\/Ma2KHKye5R8\/s400\/_6.jpg\" border=\"0\" \/> <\/p>\n<p align=\"justify\">As\u00ed, afirm\u00f3 que \u00ablas primeras turistas que llegaron con bikini ayudaron m\u00e1s a la Transici\u00f3n que muchos discurso pol\u00edticos\u00bb. No fue una afirmaci\u00f3n fr\u00edvola, sino argumentada en el hecho de que el turismo y la emigraci\u00f3n -hab\u00eda entonces casi tres millones de espa\u00f1oles en el extranjero- fueron fen\u00f3menos que coadyuvaron poderosamente a \u00abla revoluci\u00f3n cultural\u00bb que germin\u00f3 en la sociedad y actu\u00f3 como palanca del cambio pol\u00edtico.\u201d<\/p>\n<p>Uno, que siempre ha admirado a Alfonso Guerra, aunque en su momento fuera pol\u00edticamente incorrecto decirlo, se alegra especialmente por esta interpretaci\u00f3n suya de la Transici\u00f3n, m\u00e1xime porque la vivi\u00f3 en primera persona. Que eso era lo que me dec\u00edan muchos cr\u00edticos: que hablaba de cosas que no conoc\u00eda, por no haberlas presenciado en vivo y en directo.<\/p>\n<p>Pues mira. Ah\u00ed est\u00e1 Alfonso, defendiendo la democracia del bikini. <\/p>\n<p align=\"justify\"> <\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5184551511631366610\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp2.blogger.com\/_r6VY1mvj3jk\/R_M6IYKAidI\/AAAAAAAABI4\/Rn3MMLVQsXY\/s400\/_8.jpg\" border=\"0\" \/> <\/p>\n<p align=\"justify\">Y, por eso, sigo manteniendo que pocas cosas m\u00e1s \u00fatiles para luchar contra el integrismo religioso que viajar a las zonas del mundo en que \u00e9stos proliferan y lucir, con orgullo, una cabellera rubia, un piercing en la ceja, unos abdominales morenos o unas pantorrillas al aire.<\/p>\n<p>No se trata de faltar al respeto a nadie. Ni mucho menos. Se trata de mostrar una actitud personal libre. En algunos momentos puede resultar duro y hasta violento. Como cuando aquel juez le dec\u00eda a su hijo que le tirara piedras a las dos chicas que tomaban el sol, haciendo top less, en una playa espa\u00f1ola, antes de llamar a las autoridades para que las arrestaran, por exhibici\u00f3n imp\u00fadica. Eso pasaba en Espa\u00f1a no hace muchos a\u00f1os. No lo olvidemos.<\/p>\n<p>As\u00ed que, muchas gracias a Alfonso Guerra por, de una forma tan sencilla y tan clara, explicar c\u00f3mo la sociolog\u00eda del cuerpo tiene tanta o m\u00e1s importancia que las sociolog\u00edas ideol\u00f3gicas, filos\u00f3ficas y econ\u00f3micas.<\/p>\n<p>Una lecci\u00f3n memorable.<\/p>\n<p>Jes\u00fas Lens Espinosa de los Monteros. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Recuperamos unas notas, escritas hace unos meses, que ten\u00edamos por ah\u00ed sepultadas. Ahora que llega el calor, hablemos de bikinis.Una vez escrib\u00ed que, en nuestro proceso de consolidaci\u00f3n democr\u00e1tica, las turistas suecas semidesnudas tuvieron mucha m\u00e1s importancia que las haza\u00f1as de tanto y tanto jovenzuelo, corriendo delante de los grises y reuni\u00e9ndose en interminables asambleas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-144","post","type-post","status-publish","format-standard","hentry","category-opinion"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=144"}],"version-history":[{"count":0,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/144\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}