{"id":13592,"date":"2013-02-10T00:45:36","date_gmt":"2013-02-09T23:45:36","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=13592"},"modified":"2013-02-10T00:45:36","modified_gmt":"2013-02-09T23:45:36","slug":"esto-que-es","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/esto-que-es\/","title":{"rendered":"Esto que es"},"content":{"rendered":"<p style=\"text-align: justify;\">Tercera entrada sobre formas de conducirse en sociedad, cuando algo nos cabrea y escapa a nuestro control. Si empezamos por <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/te-estas-ganando-una-hostia\/\" target=\"_blank\">esta amenaza, de Santos Trinidad<\/a>, muy clara y dura; seguimos con esta otra expresi\u00f3n de malestar, <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/a-la-mierda\/\" target=\"_blank\">con Fernando Fern\u00e1n G\u00f3mez y Labordeta como maestros<\/a>.<\/p>\n<p style=\"text-align: justify;\">Pero si queremos ser m\u00e1s comedidos, siempre nos quedar\u00e1n Mat\u00edas y su c\u00e9lebre&#8230;<\/p>\n<p><object width=\"420\" height=\"315\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/zeft9c6CITs?version=3&amp;hl=es_ES\" \/><param name=\"allowfullscreen\" value=\"true\" \/><\/object><\/p>\n<p style=\"text-align: justify;\">Esta de Mauricio, m\u00e1s afectada, creemos que tiene menos empaque. En cualquier caso, tambi\u00e9n puede ser \u00fatil, con una entonaci\u00f3n m\u00e1s despreciativa que explosiva:<\/p>\n<p><object width=\"560\" height=\"315\" classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"allowFullScreen\" value=\"true\" \/><param name=\"allowscriptaccess\" value=\"always\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/OiIk_fozLgs?version=3&amp;hl=es_ES\" \/><param name=\"allowfullscreen\" value=\"true\" \/><\/object><\/p>\n<p style=\"text-align: justify;\">\u00bfSe te ocurren otras maneras de reconducir la ira y la negatividad? Ponte en contacto con Pateando el Mundo. Y no dejes de seguirme en Twitter: @jesus_lens<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tercera entrada sobre formas de conducirse en sociedad, cuando algo nos cabrea y escapa a nuestro control. Si empezamos por esta amenaza, de Santos Trinidad, muy clara y dura; seguimos con esta otra expresi\u00f3n de malestar, con Fernando Fern\u00e1n G\u00f3mez y Labordeta como maestros. Pero si queremos ser m\u00e1s comedidos, siempre nos quedar\u00e1n Mat\u00edas y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[8052,32,15],"tags":[8069,8064,32,8056,8055,8063,8068,8062,8066,8065,8067],"class_list":["post-13592","post","type-post","status-publish","format-standard","hentry","category-frases-celebres","category-humor","category-videos","tag-civismo","tag-explosion-de-ira","tag-humor","tag-insultar","tag-insultos","tag-ira","tag-manual-de-urbanidad","tag-pero-esto-que-es","tag-pero-esto-que-es-mauricio","tag-pero-esto-que-es-prats","tag-urbanidad"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/13592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=13592"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/13592\/revisions"}],"predecessor-version":[{"id":13594,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/13592\/revisions\/13594"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=13592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=13592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=13592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}