{"id":135,"date":"2008-03-29T17:30:00","date_gmt":"2008-03-29T16:30:00","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=135"},"modified":"2008-03-29T17:30:00","modified_gmt":"2008-03-29T16:30:00","slug":"como-perder-un-cliente-en-media-hora","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/como-perder-un-cliente-en-media-hora\/","title":{"rendered":"C\u00d3MO PERDER UN CLIENTE EN MEDIA HORA"},"content":{"rendered":"<table id=\"HB_Mail_Container\" height=\"100%\" cellspacing=\"0\" cellpadding=\"0\" width=\"100%\" border=\"0\" unselectable=\"on\">\n<tbody>\n<tr height=\"100%\" width=\"100%\" unselectable=\"on\">\n<td id=\"HB_Focus_Element\" valign=\"top\" width=\"100%\" background=\"\" height=\"250\" unselectable=\"off\">\n<div align=\"justify\">El viernes por la ma\u00f1ana me tengo un curso en la ESNA, sita en lo m\u00e1s alto de la calle Reyes Cat\u00f3licos. Como empezamos a las 9 de la ma\u00f1ana, me gusta llegar a las inmediaciones a eso de las 8.15 u 8.30 para tomar un par de caf\u00e9s y media tostada de mantequilla, echando un vistazo a la prensa, que compro en el quiosco de Plaza Nueva.<\/p>\n<p>El Caf\u00e9 Lisboa siempre est\u00e1 atestado, pero hay uno en las inmediaciones que est\u00e1 bien: buen decente, varios peri\u00f3dicos para los clientes y m\u00fasica agradable. Nada especial, pero un sitio agradable.<\/p>\n<p>Ayer viernes, de primeras, el bar no estaba abierto cuando sub\u00eda a comprar el peri\u00f3dico, pero alz\u00f3 la persiana justo en ese momento, as\u00ed que entr\u00e9. De primeras, no hab\u00eda pan  del d\u00eda para las tostadas. As\u00ed que me pusieron medio mollete revenido. Y, adem\u00e1s, no hab\u00eda peri\u00f3dicos, claro, con lo que me qued\u00e9 sin la raci\u00f3n matutina de Marca<\/p>\n<p>En la radio, un cutreprograma ma\u00f1anero, bien estridente. Se notaba que hab\u00edan cambiado de camarero. Tuve que pedir hasta tres veces el segundo caf\u00e9. Porque hab\u00edan entrado cuatro clientes y el nuevo no daba abasto. Y ya llegaba tarde al curso. Ped\u00ed la cuenta y pagu\u00e9 con 20 \u20ac. Me dieron el cambio de diez. Lo hice notar. Me devolvieron los 10 \u20ac, sin una disculpa.<\/p>\n<p>Y sal\u00ed por las puertas, l\u00f3gicamente, convencido de que no me ver\u00edan m\u00e1s el pelo por dicha cafeter\u00eda. Total, en la misma zona y bien pegaditas, hay del orden de siete o diez.<\/p>\n<p>\u00bfPor qu\u00e9 monta nadie una cafeter\u00eda para dar un servicio tan malo?    <\/p><\/div>\n<\/td>\n<\/tr>\n<tr hb_tag=\"1\" unselectable=\"on\">\n<td style=\"FONT-SIZE: 1pt\" height=\"1\" unselectable=\"on\">\n<div id=\"hotbar_promo\"><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>El viernes por la ma\u00f1ana me tengo un curso en la ESNA, sita en lo m\u00e1s alto de la calle Reyes Cat\u00f3licos. Como empezamos a las 9 de la ma\u00f1ana, me gusta llegar a las inmediaciones a eso de las 8.15 u 8.30 para tomar un par de caf\u00e9s y media tostada de mantequilla, echando [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-135","post","type-post","status-publish","format-standard","hentry","category-miscelanea"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=135"}],"version-history":[{"count":0,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/135\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}