{"id":13267,"date":"2013-01-15T12:01:32","date_gmt":"2013-01-15T11:01:32","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=13267"},"modified":"2013-01-15T12:01:33","modified_gmt":"2013-01-15T11:01:33","slug":"en-las-entranas-de-la-creacion-policromias","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/en-las-entranas-de-la-creacion-policromias\/","title":{"rendered":"En las entra\u00f1as de la creaci\u00f3n: Policrom\u00edas"},"content":{"rendered":"<p style=\"text-align: justify;\">CajaGRANADA despidi\u00f3 el a\u00f1o 2012 inaugurando una completa Colecci\u00f3n de Arte compuesta con lo mejor de sus fondos propios, para ser expuesta de forma continua en una de las Salas de su Museo.<\/p>\n<p style=\"text-align: justify;\">Para comenzar el a\u00f1o 2013, y con el fin de vincular entre s\u00ed las diversas actividades e iniciativas puestas en marcha por la Obra Social CajaGRANADA, la programaci\u00f3n cinematogr\u00e1fica que propone la entidad nos invita a bucear en las entra\u00f1as de la creaci\u00f3n y a profundizar en el conocimiento de determinados creadores de la historia del arte, centrando este ciclo en pintores de diversas \u00e9pocas, escuelas y estilos.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/2013\/01\/en-las-entranas-de-la-creacion-policromias\/policromias-anverso\/\" rel=\"attachment wp-att-13268\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-13268\" alt=\"Policrom\u00edas Anverso\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/01\/Policrom\u00edas-Anverso-216x300.jpg\" width=\"216\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/01\/Policrom\u00edas-Anverso-216x300.jpg 216w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/01\/Policrom\u00edas-Anverso-740x1024.jpg 740w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/01\/Policrom\u00edas-Anverso.jpg 1238w\" sizes=\"auto, (max-width: 216px) 100vw, 216px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">La pintura es un arte est\u00e1tico. Una vez que el artista fija los colores en el lienzo, el cuadro terminado quedar\u00e1 expuesto en una pared, para disfrute y deleite de los afortunados que puedan contemplarlo en un museo, en una galer\u00eda, en una colecci\u00f3n privada o, sus reproducciones, en revistas y libros de arte.<\/p>\n<p style=\"text-align: justify;\">Pero la creaci\u00f3n del cuadro -su g\u00e9nesis, idea, bocetos y ejecuci\u00f3n definitiva- conforman un proceso vivo, apasionado y, en muchas ocasiones, tempestuoso y torturador. Y as\u00ed ha sido, tambi\u00e9n, la vida de muchos de los grandes pintores de la historia.<\/p>\n<p style=\"text-align: justify;\">AulaCine CajaGRANADA se adentra en las entra\u00f1as de la creaci\u00f3n y presenta un ciclo de pel\u00edculas que narran las biograf\u00edas de algunos artistas y muestran c\u00f3mo se pintaron algunas de sus obras m\u00e1s conocidas y emblem\u00e1ticas.<\/p>\n<p style=\"text-align: justify;\">El cine, el arte, la vida y la pulsi\u00f3n creativa se dan la mano en un apasionante ciclo que dar\u00e1 color a este fr\u00edo invierno, con pel\u00edculas como \u201cLa joven de la perla\u201d, que abre la muestra el martes 15 de enero, para continuar con t\u00edtulos como \u201cEl loco del pelo rojo\u201d, \u201cSobreviviendo a Picasso\u201d, \u201cFrida\u201d, \u201cPollock\u201d, \u201cBasquiat\u201d y, para terminar, dos pel\u00edculas espa\u00f1olas tan arriesgadas como interesantes: \u201cEl sol del membrillo\u201d, el \u00faltimo filme hasta la fecha de V\u00edctor Erice, protagonizado por el pintor Antonio L\u00f3pez y \u201cLos pasos dobles\u201d, la pol\u00e9mica pel\u00edcula de Isaki Lacuesta que se alz\u00f3 con la Concha de Oro del Festival de San Sebasti\u00e1n de 2011 y en la que participa el artista multidisciplinar Miguel Barcel\u00f3.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/2013\/01\/en-las-entranas-de-la-creacion-policromias\/cine-caja-granada\/\" rel=\"attachment wp-att-13269\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-13269\" alt=\"Cine Caja granada\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/01\/Cine-Caja-granada-216x300.jpg\" width=\"216\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/01\/Cine-Caja-granada-216x300.jpg 216w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/01\/Cine-Caja-granada-740x1024.jpg 740w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/01\/Cine-Caja-granada.jpg 1238w\" sizes=\"auto, (max-width: 216px) 100vw, 216px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Un ciclo de cine a trav\u00e9s del que la Obra Social CajaGRANADA trata de acercar el mundo de la pintura a los espectadores, invit\u00e1ndoles a adentrarse en las entra\u00f1as de la creaci\u00f3n art\u00edstica para descubrir c\u00f3mo fue la vida de algunos de los pintores m\u00e1s famosos de la historia y c\u00f3mo fue el proceso que les llev\u00f3 a pintar sus obras m\u00e1s se\u00f1eras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CajaGRANADA despidi\u00f3 el a\u00f1o 2012 inaugurando una completa Colecci\u00f3n de Arte compuesta con lo mejor de sus fondos propios, para ser expuesta de forma continua en una de las Salas de su Museo. Para comenzar el a\u00f1o 2013, y con el fin de vincular entre s\u00ed las diversas actividades e iniciativas puestas en marcha por [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[33,10],"tags":[7829,10,3347,7826,7831,7830,7828,7827,3878],"class_list":["post-13267","post","type-post","status-publish","format-standard","hentry","category-arte","category-cine","tag-basquiat","tag-cine","tag-cine-cajagranada","tag-cine-granada","tag-coleccion-arte-cajagranada","tag-museo-cajagranada","tag-pintores-cine","tag-pintura-y-cine","tag-teatro-cajagranada"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/13267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=13267"}],"version-history":[{"count":3,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/13267\/revisions"}],"predecessor-version":[{"id":13272,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/13267\/revisions\/13272"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=13267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=13267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=13267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}