{"id":12871,"date":"2012-11-15T10:30:01","date_gmt":"2012-11-15T09:30:01","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=12871"},"modified":"2012-11-15T10:30:01","modified_gmt":"2012-11-15T09:30:01","slug":"co-laborando","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/co-laborando\/","title":{"rendered":"Co-laborando"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>Hoy, en IDEAL, escribimos sobre un lugar que demuestra que la modernidad puede llegar a Granada, antes que a otros sitios\u2026 \u00a1Entrad y comprobadlo!<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Laborar, seg\u00fan la RAE, es esforzarse, emplearse en algo. Por su parte, colaborar es trabajar con otra u otras personas para lograr alg\u00fan fin y, tambi\u00e9n, trabajar en una empresa sin pertenecer a su plantilla.<\/p>\n<p style=\"text-align: justify;\">Me gustan las palabras que comienzan por co, m\u00e1s all\u00e1 de las dos que el lector, a buen seguro, tiene ahora mismo en mente. Coordinaci\u00f3n, compromiso, cooperaci\u00f3n, conocimiento, compartimiento. Y colaboraci\u00f3n, por supuesto.<\/p>\n<p style=\"text-align: justify;\">Hace unos d\u00edas, Colin Bertholet me cit\u00f3 para ver c\u00f3mo hab\u00eda quedado la espectacular exposici\u00f3n de sus Garabatos Digitales (<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/2012\/09\/los-garabatos-digitales-de-colin-bertholet\/\" target=\"_blank\">mirad AQU\u00cd. Pronto, sorpresas<\/a>) en un lugar del que solo sab\u00eda a trav\u00e9s del Facebook: <a href=\"http:\/\/www.cocoroco.es\/\" target=\"_blank\">Cocoroc\u00f3<\/a>. \u00a1Vaya nombre! Eso es lo primero que piensa qui\u00e9n lo escucha. Pero, de inmediato, surge la pregunta. \u00bfQu\u00e9 es Cocoroc\u00f3? Rafa y Marcelo, cuando hacen la presentaci\u00f3n de su idea, comienzan con un v\u00eddeo repleto de humor en que varias personas tratan de explicar a la c\u00e1mara el concepto, pero son interrumpidas con las excusas m\u00e1s peregrinas y terminan\u2026 muertas de risa.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/11\/BadaBing7.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-12872\" title=\"Cocoroc\u00f3\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/11\/BadaBing7-300x183.jpg\" alt=\"\" width=\"300\" height=\"183\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/11\/BadaBing7-300x183.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/11\/BadaBing7.jpg 620w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Despu\u00e9s s\u00ed. Despu\u00e9s lo explican. Cocoroc\u00f3 es un centro de trabajo compartido, en el coraz\u00f3n de Granada. Coworking, se llama el concepto. En original y en ingl\u00e9s. Y la idea es tan sencilla como revolucionaria. \u00bfPara qu\u00e9 pagar lo mucho que cuesta una oficina, un bajo comercial, una l\u00ednea ADSL, el mobiliario, la luz, el agua, los servicios y todo lo que conlleva poner en marcha un negocio?<\/p>\n<p style=\"text-align: justify;\">En realidad, a nada que lo pensemos, en nuestro trabajo nos basta y nos sobra con una mesa, una silla, un ordenador, un m\u00f3vil y una conexi\u00f3n a Internet. Y punto. La \u00e9poca de las puertas cerradas, los despachos blindados o los paneles separadores est\u00e1 m\u00e1s acabada que la capacidad de decisi\u00f3n del gobierno espa\u00f1ol: ya hace tiempo que las empresas modernas presumen de espacios abiertos, precisamente, para favorecer entornos colaborativos.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/11\/Calma1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-12873\" title=\"Cocoroc\u00f3\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/11\/Calma1-300x191.jpg\" alt=\"\" width=\"300\" height=\"191\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/11\/Calma1-300x191.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/11\/Calma1.jpg 720w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Y eso es justo lo que propone el Coworking, un concepto que va m\u00e1s all\u00e1 de los centros de negocio al uso ya que, adem\u00e1s de compartir gastos y abaratar costes, se favorece la interacci\u00f3n entre los coworkers. A trav\u00e9s de la cercan\u00eda y mediante la organizaci\u00f3n de eventos, la dinamizaci\u00f3n de grupos y, en general, cuidando y mimando la gesti\u00f3n de un buen ambiente de trabajo que favorezca la creatividad. Y el networking. Los contactos, o sea.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/11\/Cabaret-Popescu2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-12874\" title=\"Colin en Cocoroc\u00f3\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/11\/Cabaret-Popescu2-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/11\/Cabaret-Popescu2-300x300.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/11\/Cabaret-Popescu2-150x150.jpg 150w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/11\/Cabaret-Popescu2.jpg 403w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">En Cocoroc\u00f3 encontramos techos alt\u00edsimos y una decoraci\u00f3n muy al estilo neoyorkino, como los grandes lofts del m\u00edtico Soho. Y, adem\u00e1s del enorme, luminoso y c\u00f3modo espacio de trabajo, el local tiene un altillo que, a modo de office, sirve para relajarse y tomar un respiro (y un caf\u00e9) antes de seguir currando. Y una sala m\u00e1s tranquila para cuando se necesita intimidad y recogimiento. Y, y, y\u2026 porque la clave de este nuevo sistema de trabajo, llamado a imponerse en todo el mundo, es sumar para crecer; colaborar para evolucionar. Pero vayan. Vayan a verlo y a curiosear. Porque hay veces en que el futuro, llega a Granada. \u00a1Y antes que a otros sitios!<\/p>\n<p style=\"text-align: justify;\">Jes\u00fas Lens<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy, en IDEAL, escribimos sobre un lugar que demuestra que la modernidad puede llegar a Granada, antes que a otros sitios\u2026 \u00a1Entrad y comprobadlo! Laborar, seg\u00fan la RAE, es esforzarse, emplearse en algo. Por su parte, colaborar es trabajar con otra u otras personas para lograr alg\u00fan fin y, tambi\u00e9n, trabajar en una empresa sin [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[7307,7538,7540,7539,7541,2914],"class_list":["post-12871","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-cocoroco","tag-cocoroco-granada","tag-colaborando","tag-coworking","tag-granada-futuro","tag-trabajo-en-equipo"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/12871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=12871"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/12871\/revisions"}],"predecessor-version":[{"id":12875,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/12871\/revisions\/12875"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=12871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=12871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=12871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}