{"id":11925,"date":"2012-08-01T10:26:48","date_gmt":"2012-08-01T09:26:48","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=11925"},"modified":"2012-08-01T17:46:49","modified_gmt":"2012-08-01T16:46:49","slug":"el-caballero-oscuro-2","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-caballero-oscuro-2\/","title":{"rendered":"El caballero oscuro"},"content":{"rendered":"<p style=\"text-align: justify;\">\u00bfPor qu\u00e9 los guionistas de la \u00faltima entrega de Batman no nos explican qui\u00e9n es Bane, qu\u00e9 busca y cu\u00e1les son sus principios y su filosof\u00eda mucho antes de lo que lo hacen?<\/p>\n<p style=\"text-align: justify;\">Las pel\u00edculas de superh\u00e9roes son mejores cuanto peores son los archivillanos que se enfrentan a los protagonistas. Peores en cuanto a intenciones, planes mal\u00e9ficos y prop\u00f3sitos destructores, claro. Porque, para que un malo sea malo de verdad, tiene que ser excepcionalmente bueno. El Joker interpretado por Heath Ledger, por ejemplo, fue magistral. Harvey Dos Caras, sin embargo, me convenci\u00f3 menos Aqu\u00ed, el Post \u00ab<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/2008\/08\/i-love-the-joker\/\" target=\"_blank\">I love the Joker<\/a>\u00ab.<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/08\/Alejandro-Gallo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-11926  aligncenter\" title=\"El Caballero Oscuro\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/08\/Alejandro-Gallo-202x300.jpg\" alt=\"\" width=\"202\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/08\/Alejandro-Gallo-202x300.jpg 202w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/08\/Alejandro-Gallo-691x1024.jpg 691w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/08\/Alejandro-Gallo.jpg 810w\" sizes=\"auto, (max-width: 202px) 100vw, 202px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Y, as\u00ed, llegamos a la tercera parte de la trilog\u00eda de Batman pensada, planificada, dise\u00f1ada, escrita, dirigida y producida por Christopher Nolan, uno de los grandes visionarios del cine del siglo XXI. Una trilog\u00eda oscura, tr\u00e1gica, contemplativa y existencialista en la que Batman es un personaje atormentado, introspectivo y melanc\u00f3lico, tal y como se nos presenta al comienzo de esta nueva \u00bfy \u00faltima? entrega de la saga. Al menos, la \u00faltima de Nolan y Bale, seg\u00fan han asegurado.<\/p>\n<p style=\"text-align: justify;\">Pero, en realidad, la pel\u00edcula no empieza con ese Batman minusv\u00e1lido, cojo y huidizo, sino con la primera de las tropel\u00edas cometidas por el malo de la funci\u00f3n, ese Bane cuyo rasgo m\u00e1s caracter\u00edstico es una m\u00e1scara y una voz que lo emparentan con aquel admirado, reverenciado, imitado y nunca superado Darth Vader gal\u00e1ctico.<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/08\/Caf\u00e9.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-11927  aligncenter\" title=\"Bale\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/08\/Caf\u00e9-300x189.jpg\" alt=\"\" width=\"300\" height=\"189\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/08\/Caf\u00e9-300x189.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/08\/Caf\u00e9.jpg 650w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Como si de una pel\u00edcula de James Bond se tratara, asistimos a un aperitivo espectacular y rebosante de adrenalina antes de pasar al desarrollo de los personajes, las tramas y la fijaci\u00f3n del momento espacio-temporal en que se desarrollar\u00e1 la acci\u00f3n, unos a\u00f1os despu\u00e9s de la traum\u00e1tica muerte de Harvey Dent y de la desaparici\u00f3n de Batman. Gotham es una ciudad tranquila y pac\u00edfica y Bruce Wayne vive recluido en su mansi\u00f3n, aplastado por los recuerdos.<\/p>\n<p style=\"text-align: justify;\">Pero las cosas van a cambiar. Porque ese Bane, malo mal\u00edsimo, est\u00e1 dispuesto a acabar con la concordia ciudadana. Tras una primera hora de idas y vueltas, tirando a confusa y a sosa, en la que solo se salva la felina presencia de Anne Hathaway; la pel\u00edcula empieza a coger altura con el ataque a la Bolsa, justo cuando Bane empieza a mostrarse como un l\u00edder \u00e1crata y revolucionario que trata de subvertir el orden establecido, poniendo en jaque a las grandes fortunas de Gotham.<\/p>\n<p style=\"text-align: justify;\">As\u00ed las cosas, \u00bfpara qu\u00e9 es necesario Batman? En realidad, cuando Bane muestra sus credenciales, empieza a caernos bien. Lo malo es que ya es tarde y resulta imposible tomarle el cari\u00f1o que le tomamos al Joker, por mucho que esa pelliza de cuero con forro de borrego mole tanto. M\u00e1xime porque los guionistas, sabiendo que jugaban con fuego y que, en lo m\u00e1s crudo de la crisis, los espectadores pod\u00edan identificarse con los postulados del malo de la funci\u00f3n y aceptar los sumar\u00edsimos juicios revolucionarios a los pr\u00f3ceres de Gotham; lastran a Bane con la responsabilidad de arrostrar una grave amenaza para todos los ciudadanos de la ciudad. Sin excepci\u00f3n.<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/08\/Cafe-Bar-Cinema-Presentaci\u00f3n2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-11928  aligncenter\" title=\"Catwoman\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/08\/Cafe-Bar-Cinema-Presentaci\u00f3n2-199x300.jpg\" alt=\"\" width=\"199\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/08\/Cafe-Bar-Cinema-Presentaci\u00f3n2-199x300.jpg 199w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/08\/Cafe-Bar-Cinema-Presentaci\u00f3n2.jpg 561w\" sizes=\"auto, (max-width: 199px) 100vw, 199px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Acci\u00f3n, redenci\u00f3n, sufrimiento, superaci\u00f3n, acci\u00f3n, acci\u00f3n y m\u00e1s acci\u00f3n marcan la traca final de una pel\u00edcula que termina por encajar piezas que cualquier espectador medianamente atento ya hab\u00eda encajado con anterioridad.<\/p>\n<p style=\"text-align: justify;\">Y, sin embargo, la magia del cine, de la sala llena y la pantalla gigantesca; de la m\u00fasica alta y el olor a palomitas hacen que uno salga del cine sonriendo, con ganas de tomarse una cerveza y pensando\u2026 \u00bfcu\u00e1ndo se estrenar\u00e1 \u201cEl Hombre de Acero\u201d de Snyder, cuyo tr\u00e1iler pudimos ver antes de la proyecci\u00f3n de \u201cEl caballero oscuro\u201d?<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/08\/Biblioteca.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-11929  aligncenter\" title=\"Batman\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/08\/Biblioteca-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/08\/Biblioteca-300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/08\/Biblioteca.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Y es que, efectivamente, las leyendas renacen\u2026 sobre todo, en tiempos oscuros y sombr\u00edos como estos que nos toca vivir.<\/p>\n<p style=\"text-align: justify;\">Jes\u00fas Lens<\/p>\n<p style=\"text-align: justify;\">PD.- \u00bfVeis conseguido el primer <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/2012\/07\/postpositos-veraniegos\/\" target=\"_blank\">Postp\u00f3sito de agosto<\/a>? Por cierto que Barrera, el inspirador de la idea, tambi\u00e9n ha escrito su <a href=\"http:\/\/granadablogs.com\/cableados\/2012\/07\/22\/el-verano-es-batman\/\" target=\"_blank\">Batpost<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfPor qu\u00e9 los guionistas de la \u00faltima entrega de Batman no nos explican qui\u00e9n es Bane, qu\u00e9 busca y cu\u00e1les son sus principios y su filosof\u00eda mucho antes de lo que lo hacen? Las pel\u00edculas de superh\u00e9roes son mejores cuanto peores son los archivillanos que se enfrentan a los protagonistas. Peores en cuanto a intenciones, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[7009,7006,877,6692,7008,10,6687,1698,6688,66,7003,7007],"class_list":["post-11925","post","type-post","status-publish","format-standard","hentry","category-cine","tag-anne-hathaway","tag-bane","tag-batman","tag-catwoman","tag-chistopher-nolan","tag-cine","tag-el-caballero-oscuro","tag-joker","tag-la-leyenda-renace","tag-peliculas","tag-postpositos","tag-villanos-batman"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/11925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=11925"}],"version-history":[{"count":3,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/11925\/revisions"}],"predecessor-version":[{"id":11931,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/11925\/revisions\/11931"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=11925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=11925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=11925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}