{"id":11911,"date":"2012-07-30T11:52:00","date_gmt":"2012-07-30T10:52:00","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=11911"},"modified":"2012-07-30T17:23:24","modified_gmt":"2012-07-30T16:23:24","slug":"ya-se-sabia","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/ya-se-sabia\/","title":{"rendered":"Ya se sab\u00eda&#8230;"},"content":{"rendered":"<p>&#8230; o la aplicaci\u00f3n pr\u00e1ctica de una Victoria. Pero atentos a la carta que le remite a Rajoy un periodista tan poco sospechoso de rojo, comunista o Zejiac\u00f3lito como Ans\u00f3n, y que reproducimos a continuaci\u00f3n de la imagen victoriosa de Mariano Manostijeras:<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/07\/Alejandro-Gallo4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-11912  aligncenter\" title=\"Rajoy recortes\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/07\/Alejandro-Gallo4.jpg\" alt=\"\" width=\"340\" height=\"228\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/07\/Alejandro-Gallo4.jpg 340w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/07\/Alejandro-Gallo4-300x201.jpg 300w\" sizes=\"auto, (max-width: 340px) 100vw, 340px\" \/><\/a><\/p>\n<p style=\"text-align: center;\">\n<p style=\"text-align: justify;\"><strong><em>\u00abNo s\u00e9 si tienes idea clara de lo que significa la cultura, pero no estar\u00eda de m\u00e1s que algunos de los agradadores de tu entorno te recordaran que dentro de doscientos a\u00f1os el espa\u00f1ol medio no conocer\u00e1 el nombre de Mariano Rajoy pero sabr\u00e1 muy bien qui\u00e9n es Pablo Picasso o Federico Garc\u00eda Lorca.\u00bb<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Y ahora vas&#8230; y le subes el IVA<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Jes\u00fas Lens<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\u00bfY el 30 de julio de <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/2008\/07\/30\/\">2008<\/a>, <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/2009\/07\/30\/\">2009<\/a>, <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/2010\/07\/30\/\">2010<\/a> y <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/2011\/07\/30\/\">2011<\/a>?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8230; o la aplicaci\u00f3n pr\u00e1ctica de una Victoria. Pero atentos a la carta que le remite a Rajoy un periodista tan poco sospechoso de rojo, comunista o Zejiac\u00f3lito como Ans\u00f3n, y que reproducimos a continuaci\u00f3n de la imagen victoriosa de Mariano Manostijeras: \u00abNo s\u00e9 si tienes idea clara de lo que significa la cultura, pero [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[32,7,6],"tags":[6994,6993,6989,6990,6992,6991],"class_list":["post-11911","post","type-post","status-publish","format-standard","hentry","category-humor","category-imagenes","category-opinion","tag-anson-contra-rajoy","tag-carta-anson-rajoy","tag-rajoy-recortes","tag-rajoy-v","tag-v-vendetta","tag-victoria-rajoy"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/11911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=11911"}],"version-history":[{"count":3,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/11911\/revisions"}],"predecessor-version":[{"id":11914,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/11911\/revisions\/11914"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=11911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=11911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=11911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}