{"id":11756,"date":"2012-06-29T16:00:14","date_gmt":"2012-06-29T15:00:14","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=11756"},"modified":"2012-06-29T16:08:25","modified_gmt":"2012-06-29T15:08:25","slug":"caso-cerrado-de-cesar-giron-premio-novela-negra-ciudad-de-carmona","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/caso-cerrado-de-cesar-giron-premio-novela-negra-ciudad-de-carmona\/","title":{"rendered":"Caso cerrado, de C\u00e9sar Gir\u00f3n, Premio Novela Negra Ciudad de Carmona"},"content":{"rendered":"<p style=\"text-align: justify;\">Me dio mucha alegr\u00eda que Javier Ortega me propusiera formar parte del jurado que acaba de hacer p\u00fablico el fallo de la sexta edici\u00f3n del Premio de Novela Negra Ciudad de Carmona, convocado por la editorial andaluza Almuzara y que tantas alegr\u00edas nos ha dado en los \u00faltimos a\u00f1os.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Autores que tambi\u00e9n son amigos, como Amir Valle, Antonio Lozano, Jos\u00e9 Luis Mu\u00f1oz o Guillermo Orsi se hicieron con el prestigioso galard\u00f3n en alguna de sus anteriores ediciones.  Precisamente fue en Carmona donde se estrech\u00f3 mi amistad con Orsi, aquel a\u00f1o en que pasamos horas y horas hablando de literatura, de Argentina, Espa\u00f1a, econom\u00eda, pol\u00edtica\u2026<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Creo que he le\u00eddo casi todos los Premios Ciudad de Carmona. Aunque me falta, parad\u00f3jicamente, el del a\u00f1o pasado, de \u00c1ngel Remis-Saucedo, compa\u00f1ero jurado este a\u00f1o. Una laguna que pienso llenar m\u00e1s pronto que tarde.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Tres archivos digitales y cientos de p\u00e1ginas por leer. Y no mucho tiempo por delante. Pero sarna con gusto no pica y, tirando de iPad, nos atiborramos de mucha y buena literatura criminal. Tres novelas, tres pseud\u00f3nimos, tres historias.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\u00bfFue casualidad? No lo s\u00e9. Pero me llev\u00e9 un sobresalto cuando, al empezar a leer el tercer archivo (el concepto \u201cmanuscrito\u201d ya es pura arqueolog\u00eda), me encontr\u00e9 con unas primeras referencias a Granada. Ya me hab\u00eda gustado el arranque, con un abogado como protagonista. Y con unos secundarios con presencia y fuerza en la narraci\u00f3n. Y, adem\u00e1s, \u00a1Granada!, negra y criminal.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Ah\u00ed me saltaron las alarmas. Recuerdo que par\u00e9 en seco la lectura, me calc\u00e9 las zapatillas y sal\u00ed a correr. \u00bfNo me estar\u00eda dejando influir por un cierto provincianismo lector, al discurrir los personajes por la Granada de finales de los sesenta, entre la Carrera del Darro, Plaza Nueva, el Rey Chico y algunos de sus bares y cafeter\u00edas?<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Redobl\u00e9 mis alarmas lectoras, al regresar a la lectura. Incluso volv\u00ed a leer parte de lo le\u00eddo\u2026 \u00a1y no! En absoluto. Para nada. La novela me estaba enganchando con toda justicia y lo mismo me habr\u00eda gustado si aconteciera en Segovia o en Sebastopol. Aunque, desde luego, me gusta, me encanta que sea Granada el escenario de una historia que rezuma realismo a raudales. Por ejemplo, el momento en que IDEAL y su joven director, Melchor S\u00e1iz Pardo, juegan un papel importante en la trama.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Y lleg\u00f3 el final de la lectura. Y la discusi\u00f3n y la votaci\u00f3n. Y los nervios. Y el veredicto de un jurado que determin\u00f3 que s\u00ed. Que la ganadora era \u201cCaso cerrado\u201d. Con todo merecimiento, pero sin desmerecer a las otras finalistas.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Un jurado que, en el acta, <em>\u201cvalora especialmente la minuciosa y absorbente narraci\u00f3n de un turbio suceso acaecido en la Granada de las postrimer\u00edas del franquismo, que revela el influjo de los poderes dominantes entonces, as\u00ed como la sobresaliente evocaci\u00f3n de la sociedad de la \u00e9poca en sus m\u00e1s variados perfiles. Asimismo, se pondera la figura del personaje central de la trama, un jurista comprometido, capaz de poner su conocimiento y tes\u00f3n al servicio de causas poco lucrativas, erigi\u00e9ndose as\u00ed en s\u00edmbolo de una solidaridad, hoy como entonces, tan necesaria.\u201d<\/em><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Una novela cuya <strong><em>\u201ctrama de la obra transcurre en los estertores de la dictadura franquista, en la que un afamado criminalista, Celso Costa, se encarga de la defensa de un cliente que se ha confesado culpable del homicidio de un hombre cuyo cad\u00e1ver apareci\u00f3 bajo el bosque de la Alhambra. El imputado es un guardacoches tullido al que seguidamente se relaciona con la desaparici\u00f3n de una joven prostituta. A Celso le atrae la singularidad del acusado y acepta el defenderlo para saldar una antigua cuenta pendiente. Un caso que abarcar\u00e1 m\u00e1s de treinta a\u00f1os de su vida profesional que si consigue resolverlo, estar\u00e1 en condiciones de poner punto final a su brillante carrera jur\u00eddica.\u201d<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/06\/Caso-cerrado.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-11758\" title=\"Caso cerrado\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/06\/Caso-cerrado-195x300.jpg\" alt=\"\" width=\"195\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/06\/Caso-cerrado-195x300.jpg 195w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/06\/Caso-cerrado-665x1023.jpg 665w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/06\/Caso-cerrado.jpg 1689w\" sizes=\"auto, (max-width: 195px) 100vw, 195px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">La sorpresa, la alegr\u00eda, al abrir la plica y saber que el autor de la novela es C\u00e9sar Gir\u00f3n, afamado abogado granadino con un profundo conocimiento no solo de su profesi\u00f3n, sino de la historia y la geograf\u00eda granadinas, con especial atenci\u00f3n a su historia negra y criminal, en la que es un aut\u00e9ntico especialista, como ha puesto de manifiesto en varias de sus publicaciones anteriores.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\u00a1Enhorabuena a C\u00e9sar y a la editorial Almuzara! Estoy seguro de que \u201cCaso cerrado\u201d tendr\u00e1 el \u00e9xito que se merece y que ser\u00e1 una novela que dar\u00e1 mucho, pero que mucho que hablar, al narrar una historia radicalmente basada en hechos reales. Unos hechos que, seguramente, incomodar\u00e1n a m\u00e1s de uno\u2026<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Jes\u00fas jurado Lens<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Me dio mucha alegr\u00eda que Javier Ortega me propusiera formar parte del jurado que acaba de hacer p\u00fablico el fallo de la sexta edici\u00f3n del Premio de Novela Negra Ciudad de Carmona, convocado por la editorial andaluza Almuzara y que tantas alegr\u00edas nos ha dado en los \u00faltimos a\u00f1os. Autores que tambi\u00e9n son amigos, como [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[6865,6866,2929,6867,6869,6868,6870],"class_list":["post-11756","post","type-post","status-publish","format-standard","hentry","category-negra-y-criminal","tag-caso-cerrado","tag-caso-cerrado-cesar-giron","tag-cesar-giron","tag-giron-ciudad-carmona","tag-novela-negra-almuzara","tag-premio-novela-negra-ciudad-carmona","tag-tapa-negra"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/11756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=11756"}],"version-history":[{"count":3,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/11756\/revisions"}],"predecessor-version":[{"id":11759,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/11756\/revisions\/11759"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=11756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=11756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=11756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}