{"id":11751,"date":"2012-06-29T08:18:49","date_gmt":"2012-06-29T07:18:49","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=11751"},"modified":"2012-06-29T08:18:49","modified_gmt":"2012-06-29T07:18:49","slug":"los-finalistas-de-la-eurocopa-se-plantan-en-la-cumbre","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/los-finalistas-de-la-eurocopa-se-plantan-en-la-cumbre\/","title":{"rendered":"Los finalistas de la Eurocopa se plantan en la Cumbre"},"content":{"rendered":"<p style=\"text-align: justify;\">Y, parece, que Espa\u00f1a e Italia han salido con bien de su plante y que Europa cede a sus peticiones para apoyar a la Banca de forma directa. Es llamativo que\u00a0la prensa de hoy abra con dos im\u00e1genes ic\u00f3nicas que concitan todas las miradas, comentarios, cr\u00edticas y admiraciones. Y ambas son protagonizadas por futbolistas, sin embargo. Uno italiano y otro espa\u00f1ol, curiosamente. \u00a1La de lecturas que tienen estas dos fotograf\u00edas!<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/06\/065.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-11753  aligncenter\" title=\"Balotelli Hulk\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/06\/065.jpg\" alt=\"\" width=\"600\" height=\"396\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/06\/065.jpg 600w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/06\/065-300x198.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/06\/Biblioteca9.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-11754\" title=\"Ramos confianza\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/06\/Biblioteca9.jpg\" alt=\"\" width=\"418\" height=\"306\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/06\/Biblioteca9.jpg 418w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/06\/Biblioteca9-300x219.jpg 300w\" sizes=\"auto, (max-width: 418px) 100vw, 418px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Los titulares del grupo Vocento se\u00f1alan que <strong><em>Italia desnuda a Alemania<\/em><\/strong>, partiendo de la foto de Hulk-Balotelli y el gesto de Ramos, despu\u00e9s de tirar su famoso penalti, da m\u00e1s confianza a la Marca Espa\u00f1a que la declaraci\u00f3n m\u00e1s altisonante de cualquier pol\u00edtico. \u00bfY si esta imagen de Sergio marca un antes y un despu\u00e9s en el devenir de nuestro pa\u00eds? \u00bfY si, justo ahora, empieza a terminarse la crisis, que parece que la Cumbre va bien? Que cada cu\u00e1l saque las conclusiones que quiera&#8230;<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Jes\u00fas <em><strong>imaginativo <\/strong><\/em>Lens<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Y, parece, que Espa\u00f1a e Italia han salido con bien de su plante y que Europa cede a sus peticiones para apoyar a la Banca de forma directa. Es llamativo que\u00a0la prensa de hoy abra con dos im\u00e1genes ic\u00f3nicas que concitan todas las miradas, comentarios, cr\u00edticas y admiraciones. Y ambas son protagonizadas por futbolistas, sin [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[13,8,7,6],"tags":[6862,6864,91,50,6845,6553,6863],"class_list":["post-11751","post","type-post","status-publish","format-standard","hentry","category-deporte-vida-empresa","category-deportes","category-imagenes","category-opinion","tag-balotelli","tag-balotelli-hulk","tag-crisis","tag-deporte","tag-europa","tag-sergio-ramos","tag-sergio-ramos-confianza"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/11751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=11751"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/11751\/revisions"}],"predecessor-version":[{"id":11755,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/11751\/revisions\/11755"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=11751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=11751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=11751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}