{"id":11660,"date":"2012-06-18T00:13:08","date_gmt":"2012-06-17T23:13:08","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=11660"},"modified":"2012-06-18T10:14:03","modified_gmt":"2012-06-18T09:14:03","slug":"corriendo-por-el-asfaltado-valle-de-lecrin","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/corriendo-por-el-asfaltado-valle-de-lecrin\/","title":{"rendered":"Corriendo por el asfaltado Valle de Lecr\u00edn"},"content":{"rendered":"<p style=\"text-align: justify;\">Ha sido dura y rompepiernas la carrera. Pero, adem\u00e1s, fea, \u00e1spera, calurosa y desabrida. Y, seguramente por ello, ha resultado ser, individualmente, una de las mejores carreras de la temporada (Clasificado el n\u00famero 313 , invirtiendo 51 minutos largos en 11 exigentes kms)<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\u00a1Uno es uno y sus contradicciones!<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Uno, que no bebe nunca durante sus entrenamientos, hubo un momento que cre\u00eda desfallecer si no se refrescaba la boca, la saliva convertida en una pasta blanca y los labios quemados y resecos por el sol, que ca\u00eda a plomo durante pr\u00e1cticamente todo el recorrido.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Un recorrido que no pasar\u00e1 a la historia por su belleza, precisamente. \u00a1Qu\u00e9 empacho de asfalto, autov\u00eda, arc\u00e9n y cuneta! Y yo que pensaba que \u00edbamos a correr entre naranjos y limoneros\u2026 \u00a1que \u00e9sta era la primera vez que participaba en la carretera del Valle! Menos mal que la buena gente de D\u00farcal animaba y aplaud\u00eda en el doble recorrido que transcurr\u00eda por sus calles.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Lo mejor: que nos juntamos un buen grupo de amigos y familia, casualmente reunidos en Granada este fin de semana. Lo malo: que no tenemos ni camiseta conmemorativa del evento ni jam\u00f3n con que celebrar el encuentro entre hermanos y cu\u00f1ados; entre galgos y gacelas y percherones.<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/06\/Biblioteca3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-11662  aligncenter\" title=\"Carrera Valle Lecr\u00edn\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/06\/Biblioteca3.jpg\" alt=\"\" width=\"403\" height=\"403\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/06\/Biblioteca3.jpg 403w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/06\/Biblioteca3-150x150.jpg 150w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/06\/Biblioteca3-300x300.jpg 300w\" sizes=\"auto, (max-width: 403px) 100vw, 403px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Pero era domingo, hab\u00eda carrera, hab\u00eda que correr y hemos corrido.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Enhorabuena a las miles de personas que, hoy tambi\u00e9n, participaban en la Carrera de la Mujer, contra el C\u00e1ncer. L\u00e1stima que hayan coincidido en el calendario. \u00a1Ser\u00e1 por domingos!<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">L\u00e1stima tambi\u00e9n que, ahora que empezamos a encontrarnos mejor, llegue mi particular cerrojazo al brillante Circuito de Fondo de Diputaci\u00f3n hasta septiembre, esperemos que en la dura y exigente Media Marat\u00f3n del Melocot\u00f3n, en Guadix.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Pero dej\u00e9monos de lamentos. Que en este tiempo de incertidumbres, dudas y desvelos es imprescindible encontrar actividades que nos permiten seguir anclados a una vida activa, alegre y satisfactoria. Como correr. Como jugar al baloncesto con los amigos. Como compartir, despu\u00e9s, una Alhambra helada para comentarlo. Y celebrarlo.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Porque hoy es domingo y aqu\u00ed seguimos.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Jes\u00fas <strong><em>endomingado<\/em><\/strong> Lens<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ha sido dura y rompepiernas la carrera. Pero, adem\u00e1s, fea, \u00e1spera, calurosa y desabrida. Y, seguramente por ello, ha resultado ser, individualmente, una de las mejores carreras de la temporada (Clasificado el n\u00famero 313 , invirtiendo 51 minutos largos en 11 exigentes kms) \u00a1Uno es uno y sus contradicciones! Uno, que no bebe nunca durante [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[34,8],"tags":[3053,6812,34,6811,1988,6809,6810,6813,6808],"class_list":["post-11660","post","type-post","status-publish","format-standard","hentry","category-correr","category-deportes","tag-circuito-fondo-diputacion","tag-circuito-fondo-diputacion-granada","tag-correr","tag-correr-en-familia","tag-fondo","tag-gacela","tag-galgo","tag-resultado-circuito-fondo-diputacion","tag-resultados-carrera-lecrin"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/11660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=11660"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/11660\/revisions"}],"predecessor-version":[{"id":11663,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/11660\/revisions\/11663"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=11660"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=11660"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=11660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}