{"id":116,"date":"2008-03-13T10:25:00","date_gmt":"2008-03-13T09:25:00","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=116"},"modified":"2008-03-13T10:25:00","modified_gmt":"2008-03-13T09:25:00","slug":"balance","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/balance\/","title":{"rendered":"BALANCE"},"content":{"rendered":"<p>Queridos amigos, transcurrido un mes y medio de nacido este Blog, desde el pr\u00f3ximo s\u00e1bado nos tomamos un respiro de unos d\u00edas. La Semana Santa siempre es buena \u00e9poca para hacer un par\u00f3n en la actividad cotidiana y, claro, para viajar.<\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5177155478869946258\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp2.blogger.com\/_r6VY1mvj3jk\/R9jzenECr5I\/AAAAAAAAA8c\/9MM8QmegLZ8\/s400\/_6.jpg\" border=\"0\" \/> <\/p>\n<p align=\"justify\">Este a\u00f1o, con un grupo de amigos, Sacai y yo nos vamos al Senegal, un pa\u00eds africano que siempre quise conocer y al que, hasta ahora, nunca he ido.<\/p>\n<p>Un mes y medio de vida de esta Bit\u00e1cora, que va por las 20.000 visitas, con una media de cerca de 500 descargas diarias. Que ya est\u00e1 bien.<\/p>\n<p>Como hab\u00e9is podido ver, poco a poco le hemos incorporado distintos gadgets a la bit\u00e1cora, del geolocalizador que se\u00f1ala el punto de conexi\u00f3n de los amigos on line a las listas de v\u00ednculos que enlazan con informaci\u00f3n sobre libros y pel\u00edculas, los v\u00eddeos o actuaciones musicales que m\u00e1s me gustan o tr\u00e1ilers y secuencias de pel\u00edculas de lo m\u00e1s variado. <\/p>\n<p align=\"justify\"> <\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5177155483164913586\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp3.blogger.com\/_r6VY1mvj3jk\/R9jze3ECr7I\/AAAAAAAAA8s\/ox1lfgLmjO0\/s400\/_8.jpg\" border=\"0\" \/> <\/p>\n<p align=\"justify\">Un reflejo, en fin, de por d\u00f3nde van nuestros gustos, intereses y aficiones. Le hemos puesto lo de las citas y las convocatorias, algunas im\u00e1genes que nos resultan \u00edntimamente evocadoras y esas frases lapidarias, esas perlas de la sabidur\u00eda universal, que vamos cambiando cada poco tiempo y de las que s\u00f3lo queda rastro en la memoria de los lectores.<\/p>\n<p>Imagino que a cada cu\u00e1l le gustar\u00e1n m\u00e1s unas cosas y menos otras. Es ley de vida. Eso s\u00ed, espero que el resultado global est\u00e9 siendo bueno y esas mejoras sean para bien. <\/p>\n<p align=\"justify\"> <\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5177155483164913570\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp3.blogger.com\/_r6VY1mvj3jk\/R9jze3ECr6I\/AAAAAAAAA8k\/P4nBHVEoqdU\/s400\/_7.jpg\" border=\"0\" \/> <\/p>\n<p align=\"justify\">Lo m\u00e1s atractivo, quiz\u00e1, sea el tema de las encuestas. Si Obama le va ganando a Hillary por una brutal diferencia (el 80% de los 47 votos emitidos hasta ahora han ido para Obama), el 63% de los seguidores de la bit\u00e1cora se decant\u00f3 por ZP como pr\u00f3ximo Presidente del gobierno espa\u00f1ol, con una participaci\u00f3n de 86 votantes.<\/p>\n<p>La otra encuesta, sobre los temas que m\u00e1s nos preocupan, cosech\u00f3 90 sufragios, resultando que el \u201ctema estrella\u201d es la Educaci\u00f3n, con 34 votos (37%). <\/p>\n<p align=\"justify\"> <\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5177155487459880898\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp0.blogger.com\/_r6VY1mvj3jk\/R9jzfHECr8I\/AAAAAAAAA80\/o6acIqD9c6w\/s400\/_11.jpg\" border=\"0\" \/> <\/p>\n<p align=\"justify\">15 votos han ido para la cuesti\u00f3n del desempleo (16%) y 14 para la vivienda (15%)<\/p>\n<p>El medio ambiente ha cosechado 10 sufragios, la inmigraci\u00f3n, 5. La sanidad 6; el terrorismo 3. Otros 3 votos se han decantado por \u201cotras cuestiones\u201d sin poder precisar cu\u00e1les son esos otros temores o preocupaciones.<\/p>\n<p>Y aunque estas encuestas no son cient\u00edficas, nos sirven de muestra sobre qu\u00e9 temas nos interesan m\u00e1s, informaci\u00f3n que utilizaremos para ir escribiendo reflexiones y art\u00edculos en las pr\u00f3ximas semanas, que nos sirvan de debate, discusi\u00f3n y enriquecimiento.<\/p>\n<p>Esta bit\u00e1cora la hacemos entre todos. Los comentarios, las discusiones, las propuestas, las cr\u00edticas&#8230; todo ello es esencial para que sigamos manteniendo este idilio virtual que tantas alegr\u00edas y satisfacciones nos da. <\/p>\n<p align=\"justify\"> <\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5177155474574978946\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp1.blogger.com\/_r6VY1mvj3jk\/R9jzeXECr4I\/AAAAAAAAA8U\/9WWi62HQyMI\/s400\/_4.jpg\" border=\"0\" \/> <\/p>\n<p align=\"justify\">20.000 visitas que van por vosotros.<\/p>\n<p>\u00a1Un abrazo fraternal!<\/p>\n<p>Jes\u00fas Lens, piloto de esta Tripulaci\u00f3n que patea el mundo, sin prisa y sin pausa. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Queridos amigos, transcurrido un mes y medio de nacido este Blog, desde el pr\u00f3ximo s\u00e1bado nos tomamos un respiro de unos d\u00edas. La Semana Santa siempre es buena \u00e9poca para hacer un par\u00f3n en la actividad cotidiana y, claro, para viajar. Este a\u00f1o, con un grupo de amigos, Sacai y yo nos vamos al Senegal, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[5,3],"tags":[],"class_list":["post-116","post","type-post","status-publish","format-standard","hentry","category-encuestas","category-miscelanea"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=116"}],"version-history":[{"count":0,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/116\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}