{"id":11242,"date":"2012-04-23T09:13:46","date_gmt":"2012-04-23T08:13:46","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=11242"},"modified":"2012-04-23T09:26:38","modified_gmt":"2012-04-23T08:26:38","slug":"ojito-con-el-cuentista","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/ojito-con-el-cuentista\/","title":{"rendered":"Ojito con el cuentista"},"content":{"rendered":"<p style=\"text-align: justify;\">Lo advert\u00eda Andr\u00e9s Neuman en su preg\u00f3n de la Feria del Libro de este a\u00f1o, saludado y recibido como combativo y comprometido, m\u00e1s all\u00e1 de esas faenas de ali\u00f1o en que suelen convertirse esos actos institucionales.<\/p>\n<p style=\"text-align: justify;\">Cuidadito con los Cuentistas, que son tipos peligrosos y sospechosos.<\/p>\n<p style=\"text-align: justify;\">Cabr\u00eda pensar que este elogio y reivindicaci\u00f3n de la narrativa breve, del cuento y del relato, es otra muestra m\u00e1s de estos de estos tiempos de recortes: un cuento es como una novela venida a menos, amputada y reducida.<\/p>\n<p style=\"text-align: justify;\">Pero no. Los cuentos tienen su propia individualidad e idiosincrasia; naturaleza, estructura y forma de venir y alumbrar el mundo. O explosionarlo.<\/p>\n<p style=\"text-align: justify;\">Estoy contento. Mucho. Coincide la reivindicaci\u00f3n del relato con una buena noticia: si pinch\u00e1is aqu\u00ed, ver\u00e9is <a href=\"http:\/\/edicionesamargord.net\/archives\/4720\" target=\"_blank\">los 20 finalistas del concurso de Relatos de Cerveza Ficci\u00f3n<\/a> en que participamos hace unas semanas. \u00a1M\u00e1s de 400 relatos se recibieron!<\/p>\n<p style=\"text-align: justify;\">Hoy celebramos el D\u00eda del Libro. Y es lunes. De Debate. Una pregunta, a botepronto:<\/p>\n<p style=\"text-align: justify;\">\u00bfCre\u00e9is que el libro convencional est\u00e1 en peligro de extinci\u00f3n, por culpa del libro electr\u00f3nico y los revolucionarios iChismes que han entrado en nuestra vida como un cicl\u00f3n?<\/p>\n<p style=\"text-align: justify;\">Y, otra m\u00e1s. \u00bfQu\u00e9 libro est\u00e1s leyendo ahora mismo? Yo, \u00e9ste:<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/04\/Boicot2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-11243  aligncenter\" title=\"La bruja de Babilonia\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/04\/Boicot2-203x300.jpg\" alt=\"\" width=\"203\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/04\/Boicot2-203x300.jpg 203w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/04\/Boicot2.jpg 400w\" sizes=\"auto, (max-width: 203px) 100vw, 203px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Y, por fin: \u00bfQu\u00e9 libro regalar\u00edas, en un impulso instant\u00e1neo, a una persona que te cae bien? Yo, \u00e9stos:<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/04\/204.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-11244  aligncenter\" title=\"Baria City Blues\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/04\/204-195x300.jpg\" alt=\"\" width=\"195\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/04\/204-195x300.jpg 195w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/04\/204-668x1024.jpg 668w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/04\/204.jpg 886w\" sizes=\"auto, (max-width: 195px) 100vw, 195px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/04\/Caf\u00e9-para-todos1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-11245  aligncenter\" title=\"Moravia\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/04\/Caf\u00e9-para-todos1-198x300.jpg\" alt=\"\" width=\"198\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/04\/Caf\u00e9-para-todos1-198x300.jpg 198w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/04\/Caf\u00e9-para-todos1.jpg 650w\" sizes=\"auto, (max-width: 198px) 100vw, 198px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Dicho lo cual, recordamos la invitaci\u00f3n para el viernes que viene:<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/04\/196.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-11247  aligncenter\" title=\"Caf\u00e9-Bar Cinema Feria del Libro Granada\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/04\/196-300x157.jpg\" alt=\"\" width=\"300\" height=\"157\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/04\/196-300x157.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/04\/196-1024x536.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Jes\u00fas<strong><em> literario<\/em><\/strong> Lens<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo advert\u00eda Andr\u00e9s Neuman en su preg\u00f3n de la Feria del Libro de este a\u00f1o, saludado y recibido como combativo y comprometido, m\u00e1s all\u00e1 de esas faenas de ali\u00f1o en que suelen convertirse esos actos institucionales. Cuidadito con los Cuentistas, que son tipos peligrosos y sospechosos. Cabr\u00eda pensar que este elogio y reivindicaci\u00f3n de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[2161,6516,930,6519,964,6521,6518,6517,6520],"class_list":["post-11242","post","type-post","status-publish","format-standard","hentry","category-general","tag-baria-city-blues","tag-cuentistas","tag-cuentos","tag-d-j-mcintosh","tag-dia-del-libro","tag-finalistas-cerveza-ficcion","tag-la-bruja-de-babilonia","tag-moravia-marcelo-lujan","tag-relatos-de-cerveza-ficcion"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/11242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=11242"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/11242\/revisions"}],"predecessor-version":[{"id":11248,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/11242\/revisions\/11248"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=11242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=11242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=11242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}