{"id":10621,"date":"2012-01-24T11:42:19","date_gmt":"2012-01-24T10:42:19","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=10621"},"modified":"2012-01-24T11:42:19","modified_gmt":"2012-01-24T10:42:19","slug":"la-chispa-de-la-vida","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/la-chispa-de-la-vida\/","title":{"rendered":"La chispa de la vida"},"content":{"rendered":"<p style=\"text-align: justify;\">Vamos con la segunda rese\u00f1a que publicamos con nuestros amigos de La Opini\u00f3n. Hoy toca una espa\u00f1ola, <a href=\"http:\/\/ocio.laopiniondemalaga.es\/cine\/criticas\/la-chispa-vida-por-jesus-lens-nws49643.html\">\u00abLa chispa de la vida\u00bb<\/a>, que est\u00e1 cosechando cr\u00edticas para todos los gustos y colores. Y es que la \u00faltima pel\u00edcula de \u00c1lex de la Iglesia no deja precisamente indiferente&#8230;<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/01\/187.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-10622  aligncenter\" title=\"La chispa de la vida\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/01\/187-300x186.jpg\" alt=\"\" width=\"300\" height=\"186\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/01\/187-300x186.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2012\/01\/187.jpg 564w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">\u00bfLa has visto? \u00bfQu\u00e9 te pareci\u00f3? Por cierto, hoy se anuncian las candidaturas a los Oscar. Parece que <a href=\"http:\/\/ocio.laopiniondemalaga.es\/cine\/criticas\/drive-quiza-mejor-pelicula-ano-por-j-lens-espinosa-nws48617.html\">\u00abDrive\u00bb<\/a>, que fue nuestra primera rese\u00f1a, ha escalado posiciones y puede dar la sorpresa. Y, sobre todo, esperamos lo mejor de \u00abChico y Rita\u00bb. \u00a1Crucemos los dedos!<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Jes\u00fas Lens<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vamos con la segunda rese\u00f1a que publicamos con nuestros amigos de La Opini\u00f3n. Hoy toca una espa\u00f1ola, \u00abLa chispa de la vida\u00bb, que est\u00e1 cosechando cr\u00edticas para todos los gustos y colores. Y es que la \u00faltima pel\u00edcula de \u00c1lex de la Iglesia no deja precisamente indiferente&#8230; \u00bfLa has visto? \u00bfQu\u00e9 te pareci\u00f3? Por cierto, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[743,10,6101,6099,6098,6100],"class_list":["post-10621","post","type-post","status-publish","format-standard","hentry","category-cine","tag-alex-de-la-iglesia","tag-cine","tag-cone-espanol","tag-jose-mota","tag-la-chispa-de-la-vida","tag-salma-hayec"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/10621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=10621"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/10621\/revisions"}],"predecessor-version":[{"id":10623,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/10621\/revisions\/10623"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=10621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=10621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=10621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}