{"id":10122,"date":"2011-11-24T10:22:54","date_gmt":"2011-11-24T08:22:54","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=10122"},"modified":"2011-11-24T11:23:53","modified_gmt":"2011-11-24T09:23:53","slug":"10122","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/10122\/","title":{"rendered":"Greenyway: Miranda, en verde"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>\u00a0&#8211; Ya te vale, Mir.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Eso le dec\u00edamos Pedro y yo, por las ma\u00f1anas, a las 8, tomando caf\u00e9. Porque nuestro querido Miranda, todo un se\u00f1or inform\u00e1tico en ejercicio, se hab\u00eda matriculado en la Facultad de Empresariales.<\/p>\n<p style=\"text-align: justify;\">Y, adem\u00e1s de ir a clase\u2026 \u00a1aprobaba! Y con buenas notas.<\/p>\n<p style=\"text-align: justify;\"><strong><em>&#8211; Ya te vale, Mir.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Eso le dec\u00edamos, cuando alg\u00fan lunes no ven\u00eda a la pe\u00f1a a jugar al baloncesto, porque estaba enfangado con alg\u00fan trabajillo inform\u00e1tico, por ah\u00ed.<\/p>\n<p style=\"text-align: justify;\"><strong><em>&#8211; Ya te vale, Mir.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Eso le dec\u00edamos cuando no se pod\u00eda quedar a tomar una ca\u00f1a, porque ten\u00eda que arreglarle a alguien la conexi\u00f3n de Internet en su casa o ten\u00eda que mirar alg\u00fan port\u00e1til endemoniado y cargado de virus.<\/p>\n<p style=\"text-align: justify;\"><strong><em><span style=\"color: #339966;\">&#8211; \u00a1\u00a1\u00a1\u00a1\u00a1\u00a1\u00a1\u00a1\u00a1\u00a1\u00a1\u00a1\u00a1\u00a1\u00a1\u00a1\u00a1\u00a1\u00a1\u00a1 YA TE VALE, MIR !!!!!!!!!!!!!!!!!<\/span><\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Eso le gritamos esta ma\u00f1ana, a las 8, tomando caf\u00e9, cuando nos habl\u00f3 de su nuevo proyecto.<\/p>\n<p style=\"text-align: justify;\">Bueno, m\u00e1s que proyecto, realidad.<\/p>\n<p style=\"text-align: justify;\">Porque nuestro querida Miranda se nos ha hecho empresario. O emprendedor. O aut\u00f3nomo. Y su reto\u00f1o, <a href=\"http:\/\/www.greenyway.com\/home\"><span style=\"color: #339966;\">Greenyway<\/span><\/a>, ya est\u00e1 on line.<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/11\/186.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-10123  aligncenter\" title=\"18\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/11\/186.jpg\" alt=\"\" width=\"180\" height=\"540\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/11\/186.jpg 180w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/11\/186-100x300.jpg 100w\" sizes=\"auto, (max-width: 180px) 100vw, 180px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Hace unos d\u00edas habl\u00e1bamos del <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/2011\/11\/empresas-y-aventuras\/\">Valor de los Empresarios<\/a>.<\/p>\n<p style=\"text-align: justify;\">Hoy traemos un ejemplo directo, real, palpable y cierto de que los Empresarios valientes y arrojados, osados y comprometidos, tambi\u00e9n existen.<\/p>\n<p style=\"text-align: justify;\">Un proyecto, adem\u00e1s, ecol\u00f3gico, sano y que apuesta por el medio ambiente y la sostenibilidad.<\/p>\n<p style=\"text-align: justify;\">Echadle un vistazo a Greenyway y dadle al <a href=\"http:\/\/www.facebook.com\/pages\/Greenyway\/175407682544088\">Me Gusta <\/a>de su p\u00e1gina de Facebook. Agregadlo a Favoritos, seguidlo de cerca y ver\u00e9is como no tard\u00e1is en uniros a nuestro canto de guerra:<\/p>\n<h2 style=\"text-align: center;\"><span style=\"color: #339966;\"><em>\u00a1Ya te vale, Mir!<\/em><\/span><\/h2>\n<p style=\"text-align: justify;\">\u00a0Jes\u00fas <strong><em>pensando en Gre<\/em><\/strong>enaway Lens<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0&#8211; Ya te vale, Mir. Eso le dec\u00edamos Pedro y yo, por las ma\u00f1anas, a las 8, tomando caf\u00e9. Porque nuestro querido Miranda, todo un se\u00f1or inform\u00e1tico en ejercicio, se hab\u00eda matriculado en la Facultad de Empresariales. Y, adem\u00e1s de ir a clase\u2026 \u00a1aprobaba! Y con buenas notas. &#8211; Ya te vale, Mir. Eso le [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[5765,5764,5759,5761,5762,5760,5557,5766,5763],"class_list":["post-10122","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-agua-embotellada","tag-botellas-aluminio","tag-greenyway","tag-jose-manuel-miranda","tag-miranda-emprendedor","tag-miranda-verde","tag-reciclaje","tag-sostenibilidad","tag-ya-te-vale-mir"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/10122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=10122"}],"version-history":[{"count":3,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/10122\/revisions"}],"predecessor-version":[{"id":10126,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/10122\/revisions\/10126"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=10122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=10122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=10122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}