{"id":10100,"date":"2011-11-22T22:26:17","date_gmt":"2011-11-22T20:26:17","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=10100"},"modified":"2011-11-22T22:40:56","modified_gmt":"2011-11-22T20:40:56","slug":"ilusionaria","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/ilusionaria\/","title":{"rendered":"Ilusionaria"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>Literatura de largo alcance. Si mi Primi est\u00e1 por medio, es que merece la pena. \u00a1Y mucho!<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">La madrugada del 26 de abril de 1986, el reactor n\u00famero 4 de la Central Nuclear de Chern\u00f3bil hizo explosi\u00f3n cerca de la frontera con Bielorrusia. Se intent\u00f3 acabar con el fuego utilizando agua, creando as\u00ed una gran nube radiactiva que el aire distribuy\u00f3 por diversos pa\u00edses europeos.<\/p>\n<p style=\"text-align: justify;\">Podr\u00eda ser el comienzo de un cuento con apenas perspectiva de final feliz, pero no lo es y, de serlo, habr\u00eda esperanza.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Han pasado 25 a\u00f1os y el aire les sigue haciendo da\u00f1o.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Tan triste y sencillo como que el material contaminante de la atm\u00f3sfera libera elementos radiactivos que el organismo reconoce como sales minerales, as\u00ed que los deja formar parte del metabolismo, provocando en el ser humano diversos da\u00f1os.  Los mayores afectados son los ni\u00f1os, por su condici\u00f3n de seres en crecimiento. Por si no fuera suficiente, a la poca esperanza sanitaria del entorno, se le suma la econ\u00f3mica.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Por todo esto, y porque no debemos olvidar, nace ILUSIONARIA. Se trata de un proyecto ben\u00e9fico en el que colaboran 20 autores y 20 ilustradores de nuestro pa\u00eds, bajo la batuta de Juan de Dios Gardu\u00f1o Cuenca (escritor y asesor editorial).<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/11\/0000012.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-10101\" title=\"Ilusionaria\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/11\/0000012.jpg\" alt=\"\" width=\"320\" height=\"236\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/11\/0000012.jpg 320w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2011\/11\/0000012-300x221.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Los nombres de los participantes, as\u00ed como sus biograf\u00edas, pueden consultarse en <a href=\"http:\/\/ilusionariaantologabenfica.blogspot.com\/\">http:\/\/ilusionariaantologabenfica.blogspot.com\/<\/a>, blog creado para la difusi\u00f3n de los avances al respecto, informaci\u00f3n de las presentaciones previstas y posibilidad de realizar un pre-pedido de la antolog\u00eda.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Dentro de ILUSIONARIA encontrar\u00e1 veinte cuentos infantiles y sus respectivas y maravillosas ilustraciones, con este ilusionante proyecto se pretende recaudar fondos que ser\u00e1n entregados, en su totalidad,  a la Asociaci\u00f3n \u201cMatrioska-Fons Mellaria\u201d. Con ellos, se cubrir\u00e1n gastos de desplazamiento y gestiones de visados de los ni\u00f1os de 7 a 17 a\u00f1os que componen el programa de acogida.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\u00bfPor qu\u00e9 traer a estos ni\u00f1os a nuestro pa\u00eds? Dos razones importantes:<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">1.- Que los niveles de material radioactivo disminuya en el organismo de los ni\u00f1os acogidos (est\u00e1 probado que se consigue con estancias de 45 a 60 d\u00edas fuera de \u201conda\u201d).<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">2.- Que puedan ser, al menos durante verano y navidad, lo que son: ni\u00f1os.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Escribamos, entre todos, este cuento.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Jes\u00fas ilusionado Lens<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">En a\u00f1os anteriores, escribimos esto: <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/2008\/11\/22\/\">2008<\/a>, <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/2009\/11\/22\/\">2009<\/a> y <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/2010\/11\/22\/\">2010<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Literatura de largo alcance. Si mi Primi est\u00e1 por medio, es que merece la pena. \u00a1Y mucho! La madrugada del 26 de abril de 1986, el reactor n\u00famero 4 de la Central Nuclear de Chern\u00f3bil hizo explosi\u00f3n cerca de la frontera con Bielorrusia. Se intent\u00f3 acabar con el fuego utilizando agua, creando as\u00ed una gran [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[9],"tags":[5744,5743,5742,5740,5741,4560],"class_list":["post-10100","post","type-post","status-publish","format-standard","hentry","category-literarios","tag-chernobil","tag-cuentos-solidarios","tag-garduno-cuenca","tag-ilusionaria","tag-juan-de-dios-garduno-cuenca","tag-laura-munoz"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/10100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=10100"}],"version-history":[{"count":3,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/10100\/revisions"}],"predecessor-version":[{"id":10103,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/10100\/revisions\/10103"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=10100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=10100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=10100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}