{"id":33505,"date":"2024-02-05T20:07:00","date_gmt":"2024-02-05T19:07:00","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2024\/02\/Dinalogos-cine-espanol.jpeg"},"modified":"2024-02-05T20:07:08","modified_gmt":"2024-02-05T19:07:08","slug":"dinalogos-cine-espanol","status":"inherit","type":"attachment","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/hablar-de-cine-negro-o-de-cualquier-color\/dinalogos-cine-espanol\/","title":{"rendered":"Di\u00e1logos cine espa\u00f1ol"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"jetpack_post_was_ever_published":false},"class_list":["post-33505","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2024\/02\/Dinalogos-cine-espanol.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"214\" height=\"300\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2024\/02\/Dinalogos-cine-espanol-214x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2024\/02\/Dinalogos-cine-espanol-214x300.jpeg 214w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2024\/02\/Dinalogos-cine-espanol-644x902.jpeg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2024\/02\/Dinalogos-cine-espanol-768x1075.jpeg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2024\/02\/Dinalogos-cine-espanol-1097x1536.jpeg 1097w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2024\/02\/Dinalogos-cine-espanol.jpeg 1417w\" sizes=\"auto, (max-width: 214px) 100vw, 214px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1417,"height":1984,"file":"2024\/02\/Dinalogos-cine-espanol.jpeg","sizes":{"medium":{"file":"Dinalogos-cine-espanol-214x300.jpeg","width":214,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2024\/02\/Dinalogos-cine-espanol-214x300.jpeg"},"large":{"file":"Dinalogos-cine-espanol-644x902.jpeg","width":644,"height":902,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2024\/02\/Dinalogos-cine-espanol-644x902.jpeg"},"thumbnail":{"file":"Dinalogos-cine-espanol-150x150.jpeg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2024\/02\/Dinalogos-cine-espanol-150x150.jpeg"},"medium_large":{"file":"Dinalogos-cine-espanol-768x1075.jpeg","width":768,"height":1075,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2024\/02\/Dinalogos-cine-espanol-768x1075.jpeg"},"1536x1536":{"file":"Dinalogos-cine-espanol-1097x1536.jpeg","width":1097,"height":1536,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2024\/02\/Dinalogos-cine-espanol-1097x1536.jpeg"},"post-thumbnail":{"file":"Dinalogos-cine-espanol-644x902.jpeg","width":644,"height":902,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2024\/02\/Dinalogos-cine-espanol-644x902.jpeg"},"first-page-thumbnail":{"file":"Dinalogos-cine-espanol-1220x480.jpeg","width":1220,"height":480,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2024\/02\/Dinalogos-cine-espanol-1220x480.jpeg"},"full":{"file":"Dinalogos-cine-espanol.jpeg","width":1417,"height":1984,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2024\/02\/Dinalogos-cine-espanol.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":33502,"source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2024\/02\/Dinalogos-cine-espanol.jpeg","_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media\/33505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=33505"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":33502,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/33502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}