{"id":33392,"date":"2023-11-21T10:16:44","date_gmt":"2023-11-21T09:16:44","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/11\/un-jurado-de-iguales.jpeg"},"modified":"2023-11-21T10:16:44","modified_gmt":"2023-11-21T09:16:44","slug":"un-jurado-de-iguales","status":"inherit","type":"attachment","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/cinco-referentes-noir-escritos-por-mujeres\/un-jurado-de-iguales\/","title":{"rendered":"un jurado de iguales"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"jetpack_post_was_ever_published":false},"class_list":["post-33392","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/11\/un-jurado-de-iguales.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"177\" height=\"300\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/11\/un-jurado-de-iguales-177x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/11\/un-jurado-de-iguales-177x300.jpeg 177w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/11\/un-jurado-de-iguales-644x1094.jpeg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/11\/un-jurado-de-iguales-768x1304.jpeg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/11\/un-jurado-de-iguales-904x1536.jpeg 904w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/11\/un-jurado-de-iguales.jpeg 942w\" sizes=\"auto, (max-width: 177px) 100vw, 177px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":942,"height":1600,"file":"2023\/11\/un-jurado-de-iguales.jpeg","sizes":{"medium":{"file":"un-jurado-de-iguales-177x300.jpeg","width":177,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/11\/un-jurado-de-iguales-177x300.jpeg"},"large":{"file":"un-jurado-de-iguales-644x1094.jpeg","width":644,"height":1094,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/11\/un-jurado-de-iguales-644x1094.jpeg"},"thumbnail":{"file":"un-jurado-de-iguales-150x150.jpeg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/11\/un-jurado-de-iguales-150x150.jpeg"},"medium_large":{"file":"un-jurado-de-iguales-768x1304.jpeg","width":768,"height":1304,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/11\/un-jurado-de-iguales-768x1304.jpeg"},"1536x1536":{"file":"un-jurado-de-iguales-904x1536.jpeg","width":904,"height":1536,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/11\/un-jurado-de-iguales-904x1536.jpeg"},"post-thumbnail":{"file":"un-jurado-de-iguales-644x1094.jpeg","width":644,"height":1094,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/11\/un-jurado-de-iguales-644x1094.jpeg"},"first-page-thumbnail":{"file":"un-jurado-de-iguales-942x480.jpeg","width":942,"height":480,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/11\/un-jurado-de-iguales-942x480.jpeg"},"full":{"file":"un-jurado-de-iguales.jpeg","width":942,"height":1600,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/11\/un-jurado-de-iguales.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":33390,"source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/11\/un-jurado-de-iguales.jpeg","_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media\/33392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=33392"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":33390,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/33390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}