{"id":32777,"date":"2023-01-16T11:55:30","date_gmt":"2023-01-16T10:55:30","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/01\/Un-policia-en-la-Luna.jpg"},"modified":"2023-01-16T11:55:30","modified_gmt":"2023-01-16T10:55:30","slug":"un-policia-en-la-luna","status":"inherit","type":"attachment","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/crimenes-e-investigaciones-extraterrestres\/un-policia-en-la-luna\/","title":{"rendered":"Un polic\u00eda en la Luna"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"jetpack_post_was_ever_published":false},"class_list":["post-32777","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/01\/Un-policia-en-la-Luna.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"188\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/01\/Un-policia-en-la-Luna-300x188.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/01\/Un-policia-en-la-Luna-300x188.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/01\/Un-policia-en-la-Luna-644x403.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/01\/Un-policia-en-la-Luna-768x480.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/01\/Un-policia-en-la-Luna.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":800,"height":500,"file":"2023\/01\/Un-policia-en-la-Luna.jpg","sizes":{"medium":{"file":"Un-policia-en-la-Luna-300x188.jpg","width":300,"height":188,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/01\/Un-policia-en-la-Luna-300x188.jpg"},"large":{"file":"Un-policia-en-la-Luna-644x403.jpg","width":644,"height":403,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/01\/Un-policia-en-la-Luna-644x403.jpg"},"thumbnail":{"file":"Un-policia-en-la-Luna-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/01\/Un-policia-en-la-Luna-150x150.jpg"},"medium_large":{"file":"Un-policia-en-la-Luna-768x480.jpg","width":768,"height":480,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/01\/Un-policia-en-la-Luna-768x480.jpg"},"post-thumbnail":{"file":"Un-policia-en-la-Luna-644x403.jpg","width":644,"height":403,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/01\/Un-policia-en-la-Luna-644x403.jpg"},"first-page-thumbnail":{"file":"Un-policia-en-la-Luna-800x480.jpg","width":800,"height":480,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/01\/Un-policia-en-la-Luna-800x480.jpg"},"full":{"file":"Un-policia-en-la-Luna.jpg","width":800,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/01\/Un-policia-en-la-Luna.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":32773,"source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2023\/01\/Un-policia-en-la-Luna.jpg","_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media\/32777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=32777"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":32773,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/32773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}