{"id":29170,"date":"2020-06-10T18:07:38","date_gmt":"2020-06-10T17:07:38","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/06\/Vi\u00f1etas-negras-Jes\u00fas-Lens.jpeg"},"modified":"2020-06-10T18:07:38","modified_gmt":"2020-06-10T17:07:38","slug":"vinetas-negras-jesus-lens","status":"inherit","type":"attachment","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/clasicos-del-noir-en-vinetas\/vinetas-negras-jesus-lens\/","title":{"rendered":"Vi\u00f1etas negras Jes\u00fas Lens"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"jetpack_post_was_ever_published":false},"class_list":["post-29170","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/06\/Vi\u00f1etas-negras-Jes\u00fas-Lens.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"171\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/06\/Vi\u00f1etas-negras-Jes\u00fas-Lens-300x171.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/06\/Vi\u00f1etas-negras-Jes\u00fas-Lens-300x171.jpeg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/06\/Vi\u00f1etas-negras-Jes\u00fas-Lens-768x438.jpeg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/06\/Vi\u00f1etas-negras-Jes\u00fas-Lens-644x367.jpeg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/06\/Vi\u00f1etas-negras-Jes\u00fas-Lens.jpeg 789w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":789,"height":450,"file":"2020\/06\/Vi\u00f1etas-negras-Jes\u00fas-Lens.jpeg","sizes":{"thumbnail":{"file":"Vi\u00f1etas-negras-Jes\u00fas-Lens-150x150.jpeg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/06\/Vi\u00f1etas-negras-Jes\u00fas-Lens-150x150.jpeg"},"medium":{"file":"Vi\u00f1etas-negras-Jes\u00fas-Lens-300x171.jpeg","width":300,"height":171,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/06\/Vi\u00f1etas-negras-Jes\u00fas-Lens-300x171.jpeg"},"medium_large":{"file":"Vi\u00f1etas-negras-Jes\u00fas-Lens-768x438.jpeg","width":768,"height":438,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/06\/Vi\u00f1etas-negras-Jes\u00fas-Lens-768x438.jpeg"},"large":{"file":"Vi\u00f1etas-negras-Jes\u00fas-Lens-644x367.jpeg","width":644,"height":367,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/06\/Vi\u00f1etas-negras-Jes\u00fas-Lens-644x367.jpeg"},"post-thumbnail":{"file":"Vi\u00f1etas-negras-Jes\u00fas-Lens-644x367.jpeg","width":644,"height":367,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/06\/Vi\u00f1etas-negras-Jes\u00fas-Lens-644x367.jpeg"},"full":{"file":"Vi\u00f1etas-negras-Jes\u00fas-Lens.jpeg","width":789,"height":450,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/06\/Vi\u00f1etas-negras-Jes\u00fas-Lens.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":29169,"source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/06\/Vi\u00f1etas-negras-Jes\u00fas-Lens.jpeg","_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media\/29170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=29170"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":29169,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/29169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}