{"id":28691,"date":"2020-02-12T19:12:20","date_gmt":"2020-02-12T18:12:20","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/02\/Zaillian.jpg"},"modified":"2020-02-12T19:12:20","modified_gmt":"2020-02-12T18:12:20","slug":"zaillian","status":"inherit","type":"attachment","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/vuelve-ripley\/zaillian\/","title":{"rendered":"Zaillian"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"jetpack_post_was_ever_published":false},"class_list":["post-28691","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/02\/Zaillian.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"299\" height=\"168\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/02\/Zaillian.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":299,"height":168,"file":"2020\/02\/Zaillian.jpg","sizes":{"thumbnail":{"file":"Zaillian-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/02\/Zaillian-150x150.jpg"},"full":{"file":"Zaillian.jpg","width":299,"height":168,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/02\/Zaillian.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":28690,"source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2020\/02\/Zaillian.jpg","_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media\/28691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=28691"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":28690,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/28690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}