{"id":26254,"date":"2018-12-13T18:12:08","date_gmt":"2018-12-13T17:12:08","guid":{"rendered":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/12\/El-Gourmet-Solitario-3.jpg"},"modified":"2018-12-13T18:12:08","modified_gmt":"2018-12-13T17:12:08","slug":"el-gourmet-solitario-3","status":"inherit","type":"attachment","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/un-gourmet-solitario-observador-y-reflexivo\/el-gourmet-solitario-3\/","title":{"rendered":"El Gourmet Solitario 3"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"jetpack_post_was_ever_published":false},"class_list":["post-26254","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/12\/El-Gourmet-Solitario-3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"212\" height=\"300\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/12\/El-Gourmet-Solitario-3-212x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/12\/El-Gourmet-Solitario-3-212x300.jpg 212w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/12\/El-Gourmet-Solitario-3-768x1084.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/12\/El-Gourmet-Solitario-3-644x909.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/12\/El-Gourmet-Solitario-3.jpg 2008w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2008,"height":2835,"file":"2018\/12\/El-Gourmet-Solitario-3.jpg","sizes":{"thumbnail":{"file":"El-Gourmet-Solitario-3-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/12\/El-Gourmet-Solitario-3-150x150.jpg"},"medium":{"file":"El-Gourmet-Solitario-3-212x300.jpg","width":212,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/12\/El-Gourmet-Solitario-3-212x300.jpg"},"medium_large":{"file":"El-Gourmet-Solitario-3-768x1084.jpg","width":768,"height":1084,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/12\/El-Gourmet-Solitario-3-768x1084.jpg"},"large":{"file":"El-Gourmet-Solitario-3-644x909.jpg","width":644,"height":909,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/12\/El-Gourmet-Solitario-3-644x909.jpg"},"post-thumbnail":{"file":"El-Gourmet-Solitario-3-644x909.jpg","width":644,"height":909,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/12\/El-Gourmet-Solitario-3-644x909.jpg"},"first-page-thumbnail":{"file":"El-Gourmet-Solitario-3-1220x480.jpg","width":1220,"height":480,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/12\/El-Gourmet-Solitario-3-1220x480.jpg"},"full":{"file":"El-Gourmet-Solitario-3.jpg","width":2008,"height":2835,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/12\/El-Gourmet-Solitario-3.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":26250,"source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/12\/El-Gourmet-Solitario-3.jpg","_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media\/26254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=26254"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":26250,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/26250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}