{"id":25445,"date":"2018-07-15T10:07:09","date_gmt":"2018-07-15T09:07:09","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/A-una-hora-de-Guadalinfo.jpg"},"modified":"2018-07-15T10:07:37","modified_gmt":"2018-07-15T09:07:37","slug":"a-una-hora-de-guadalinfo","status":"inherit","type":"attachment","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/a-una-hora-de-granada\/a-una-hora-de-guadalinfo\/","title":{"rendered":"A una hora de Guadalinfo"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"jetpack_post_was_ever_published":false},"class_list":["post-25445","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/A-una-hora-de-Guadalinfo.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/A-una-hora-de-Guadalinfo-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/A-una-hora-de-Guadalinfo-225x300.jpg 225w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/A-una-hora-de-Guadalinfo-644x859.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/A-una-hora-de-Guadalinfo.jpg 750w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Antiguo Lavadero del Padul<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":750,"height":1000,"file":"2018\/07\/A-una-hora-de-Guadalinfo.jpg","sizes":{"thumbnail":{"file":"A-una-hora-de-Guadalinfo-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/A-una-hora-de-Guadalinfo-150x150.jpg"},"medium":{"file":"A-una-hora-de-Guadalinfo-225x300.jpg","width":225,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/A-una-hora-de-Guadalinfo-225x300.jpg"},"large":{"file":"A-una-hora-de-Guadalinfo-644x859.jpg","width":644,"height":859,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/A-una-hora-de-Guadalinfo-644x859.jpg"},"post-thumbnail":{"file":"A-una-hora-de-Guadalinfo-644x859.jpg","width":644,"height":859,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/A-una-hora-de-Guadalinfo-644x859.jpg"},"first-page-thumbnail":{"file":"A-una-hora-de-Guadalinfo-750x480.jpg","width":750,"height":480,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/A-una-hora-de-Guadalinfo-750x480.jpg"},"full":{"file":"A-una-hora-de-Guadalinfo.jpg","width":750,"height":1000,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/A-una-hora-de-Guadalinfo.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":25442,"source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/07\/A-una-hora-de-Guadalinfo.jpg","_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media\/25445","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=25445"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":25442,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/25442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}