{"id":25121,"date":"2018-06-08T07:28:44","date_gmt":"2018-06-08T06:28:44","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Alcadima-salm\u00f3n.jpg"},"modified":"2018-06-08T07:28:44","modified_gmt":"2018-06-08T06:28:44","slug":"alcadima-salmon","status":"inherit","type":"attachment","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/alcadima-tradicion-andalusi-en-la-puerta-de-la-alpujarra\/alcadima-salmon\/","title":{"rendered":"Alcadima salm\u00f3n"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"jetpack_post_was_ever_published":false},"class_list":["post-25121","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Alcadima-salm\u00f3n.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Alcadima-salm\u00f3n-225x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Alcadima-salm\u00f3n-225x300.jpg 225w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Alcadima-salm\u00f3n-768x1024.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Alcadima-salm\u00f3n-644x859.jpg 644w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":3024,"height":4032,"file":"2018\/06\/Alcadima-salm\u00f3n.jpg","sizes":{"thumbnail":{"file":"Alcadima-salm\u00f3n-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Alcadima-salm\u00f3n-150x150.jpg"},"medium":{"file":"Alcadima-salm\u00f3n-225x300.jpg","width":225,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Alcadima-salm\u00f3n-225x300.jpg"},"medium_large":{"file":"Alcadima-salm\u00f3n-768x1024.jpg","width":768,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Alcadima-salm\u00f3n-768x1024.jpg"},"large":{"file":"Alcadima-salm\u00f3n-644x859.jpg","width":644,"height":859,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Alcadima-salm\u00f3n-644x859.jpg"},"post-thumbnail":{"file":"Alcadima-salm\u00f3n-644x859.jpg","width":644,"height":859,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Alcadima-salm\u00f3n-644x859.jpg"},"first-page-thumbnail":{"file":"Alcadima-salm\u00f3n-1220x480.jpg","width":1220,"height":480,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Alcadima-salm\u00f3n-1220x480.jpg"},"full":{"file":"Alcadima-salm\u00f3n.jpg","width":3024,"height":4032,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Alcadima-salm\u00f3n.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":25119,"source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2018\/06\/Alcadima-salm\u00f3n.jpg","_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media\/25121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=25121"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":25119,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/25119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}