{"id":22408,"date":"2017-05-24T13:21:18","date_gmt":"2017-05-24T12:21:18","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Enrique-Urbizu-Juan-Madrid-Granada-Noir.jpg"},"modified":"2017-05-24T13:21:18","modified_gmt":"2017-05-24T12:21:18","slug":"enrique-urbizu-juan-madrid-granada-noir-2","status":"inherit","type":"attachment","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-cineasta-y-escritor-agustin-diaz-yanes-iii-premio-granada-noir\/enrique-urbizu-juan-madrid-granada-noir-2\/","title":{"rendered":"Enrique Urbizu Juan Madrid Granada Noir"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"jetpack_post_was_ever_published":false},"class_list":["post-22408","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Enrique-Urbizu-Juan-Madrid-Granada-Noir.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Enrique-Urbizu-Juan-Madrid-Granada-Noir-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Enrique-Urbizu-Juan-Madrid-Granada-Noir-300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Enrique-Urbizu-Juan-Madrid-Granada-Noir-768x576.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Enrique-Urbizu-Juan-Madrid-Granada-Noir-644x483.jpg 644w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":3264,"height":2448,"file":"2017\/05\/Enrique-Urbizu-Juan-Madrid-Granada-Noir.jpg","sizes":{"thumbnail":{"file":"Enrique-Urbizu-Juan-Madrid-Granada-Noir-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Enrique-Urbizu-Juan-Madrid-Granada-Noir-150x150.jpg"},"medium":{"file":"Enrique-Urbizu-Juan-Madrid-Granada-Noir-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Enrique-Urbizu-Juan-Madrid-Granada-Noir-300x225.jpg"},"medium_large":{"file":"Enrique-Urbizu-Juan-Madrid-Granada-Noir-768x576.jpg","width":768,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Enrique-Urbizu-Juan-Madrid-Granada-Noir-768x576.jpg"},"large":{"file":"Enrique-Urbizu-Juan-Madrid-Granada-Noir-644x483.jpg","width":644,"height":483,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Enrique-Urbizu-Juan-Madrid-Granada-Noir-644x483.jpg"},"post-thumbnail":{"file":"Enrique-Urbizu-Juan-Madrid-Granada-Noir-644x483.jpg","width":644,"height":483,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Enrique-Urbizu-Juan-Madrid-Granada-Noir-644x483.jpg"},"first-page-thumbnail":{"file":"Enrique-Urbizu-Juan-Madrid-Granada-Noir-1220x480.jpg","width":1220,"height":480,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Enrique-Urbizu-Juan-Madrid-Granada-Noir-1220x480.jpg"},"full":{"file":"Enrique-Urbizu-Juan-Madrid-Granada-Noir.jpg","width":3264,"height":2448,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Enrique-Urbizu-Juan-Madrid-Granada-Noir.jpg"}},"image_meta":{"aperture":"2.2","credit":"","camera":"iPhone 5s","caption":"","created_timestamp":"1475964993","copyright":"","focal_length":"4.15","iso":"320","shutter_speed":"0.041666666666667","title":"","orientation":"0","keywords":[]}},"post":22401,"source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Enrique-Urbizu-Juan-Madrid-Granada-Noir.jpg","_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media\/22408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=22408"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":22401,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/22401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}