{"id":17157,"date":"2014-09-11T13:02:28","date_gmt":"2014-09-11T12:02:28","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/09\/Ciudad-delirio.jpg"},"modified":"2014-09-11T13:02:28","modified_gmt":"2014-09-11T12:02:28","slug":"ciudad-delirio","status":"inherit","type":"attachment","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/lo-que-granada-no-ve\/ciudad-delirio\/","title":{"rendered":"Ciudad delirio"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":{"jetpack_post_was_ever_published":false},"class_list":["post-17157","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/09\/Ciudad-delirio.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"208\" height=\"300\" src=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/09\/Ciudad-delirio-208x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/09\/Ciudad-delirio-208x300.jpg 208w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/09\/Ciudad-delirio.jpg 620w\" sizes=\"auto, (max-width: 208px) 100vw, 208px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":620,"height":894,"file":"2014\/09\/Ciudad-delirio.jpg","sizes":{"thumbnail":{"file":"Ciudad-delirio-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/09\/Ciudad-delirio-150x150.jpg"},"medium":{"file":"Ciudad-delirio-208x300.jpg","width":208,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/09\/Ciudad-delirio-208x300.jpg"},"full":{"file":"Ciudad-delirio.jpg","width":620,"height":894,"mime_type":"image\/jpeg","source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/09\/Ciudad-delirio.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":17153,"source_url":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/09\/Ciudad-delirio.jpg","_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media\/17157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=17157"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":17153,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/17153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}