{"id":9354,"date":"2018-10-12T16:30:57","date_gmt":"2018-10-12T14:30:57","guid":{"rendered":"https:\/\/www.granadablogs.com\/juezcalatayud\/?p=9354"},"modified":"2018-10-12T16:30:57","modified_gmt":"2018-10-12T14:30:57","slug":"visca-espana-viva-espana-viva-la-guardia-civil-visca-la-guardia-civil-y-felicidades-a-las-pilares-y-a-los-aragoneses","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2018\/10\/visca-espana-viva-espana-viva-la-guardia-civil-visca-la-guardia-civil-y-felicidades-a-las-pilares-y-a-los-aragoneses\/","title":{"rendered":"\u00a1Visca Espa\u00f1a, viva Espa\u00f1a, viva la Guardia Civil, visca la Guardia Civil!, y felicidades a las Pilares y a los aragoneses"},"content":{"rendered":"<p>&nbsp;<\/p>\n<figure id=\"attachment_8809\" aria-describedby=\"caption-attachment-8809\" style=\"width: 624px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8809 size-full\" src=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2018\/07\/rostro.jpg\" alt=\"\" width=\"624\" height=\"384\" srcset=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2018\/07\/rostro.jpg 624w, https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2018\/07\/rostro-300x185.jpg 300w\" sizes=\"auto, (max-width: 624px) 100vw, 624px\" \/><figcaption id=\"caption-attachment-8809\" class=\"wp-caption-text\">ideal.es<\/figcaption><\/figure>\n<p>Buenas, soy Emilio Calatayud. Hoy, D\u00eda de la Hispanidad o de la Fiesta Nacional, me he levantado con ganas de felicitarme y felicitaros, porque, a fin de cuentas, es la fiesta de todos los espa\u00f1oles, tambi\u00e9n de los que no quieren serlo. Tambi\u00e9n quiero felicitar a la Guardia Civil, que celebra a su patrona, la Virgen del Pilar, por el excelente trabajo que realiza cada d\u00eda para que podamos vivir m\u00e1s seguros. Y tengo que agradecer al general catal\u00e1n de la Benem\u00e9rita Pedro Garrido Roca que diera parte de su discurso en catal\u00e1n, -que, como el espa\u00f1ol, es su lengua- en la toma de posesi\u00f3n como jefe de zona en Catalu\u00f1a. Digan lo que digan, no hay una sola forma de ser catal\u00e1n.\u00a0\u00a1Visca Espa\u00f1a, viva Espa\u00f1a, viva la Guardia Civil, visca la Guardia Civil!<\/p>\n<p>Y, por supuesto, felicidades a todas las Pilares y a todos los aragoneses.<\/p>\n<p>Y gracias a todos los que hab\u00e9is elegido Granada para pasar el puente, que sois muchos. Porque en Granada cabemos todos. Y en Espa\u00f1a, tambi\u00e9n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Buenas, soy Emilio Calatayud. Hoy, D\u00eda de la Hispanidad o de la Fiesta Nacional, me he levantado con ganas de felicitarme y felicitaros, porque, a fin de cuentas, es la fiesta de todos los espa\u00f1oles, tambi\u00e9n de los que no quieren serlo. Tambi\u00e9n quiero felicitar a la Guardia Civil, que celebra a su patrona, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[680,2224],"class_list":["post-9354","post","type-post","status-publish","format-standard","hentry","category-blog","tag-guardia-civil","tag-visca"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-2qS","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/9354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=9354"}],"version-history":[{"count":4,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/9354\/revisions"}],"predecessor-version":[{"id":9358,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/9354\/revisions\/9358"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=9354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=9354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=9354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}