{"id":8912,"date":"2018-08-01T20:07:43","date_gmt":"2018-08-01T18:07:43","guid":{"rendered":"http:\/\/www.granadablogs.com\/juezcalatayud\/?p=8912"},"modified":"2018-08-01T20:07:43","modified_gmt":"2018-08-01T18:07:43","slug":"espero-que-al-recibo-de-la-presente-ya-casi-nadie-envia-postales-en-vacaciones-solo-selfies-de-esos-que-pena","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2018\/08\/espero-que-al-recibo-de-la-presente-ya-casi-nadie-envia-postales-en-vacaciones-solo-selfies-de-esos-que-pena\/","title":{"rendered":"\u00abEspero que al recibo de la presente&#8230;\u00bb, ya casi nadie env\u00eda postales en vacaciones, solo selfies de esos, \u00a1qu\u00e9 pena!"},"content":{"rendered":"<p>&nbsp;<\/p>\n<figure id=\"attachment_8915\" aria-describedby=\"caption-attachment-8915\" style=\"width: 550px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8915 size-full\" src=\"http:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2018\/08\/postales.jpg\" alt=\"\" width=\"550\" height=\"309\" srcset=\"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2018\/08\/postales.jpg 550w, https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2018\/08\/postales-300x169.jpg 300w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><figcaption id=\"caption-attachment-8915\" class=\"wp-caption-text\">El Correo<\/figcaption><\/figure>\n<p>Buenas, soy Emilio Calatayud. Acabo de llegar de la primera parte contratante de mis vacaciones y me ha dado por pensar que ya casi nadie env\u00eda postales para informar de sus veraneos. \u00a1Qu\u00e9 pena! Ya solo llegan selfies de esos a trav\u00e9s del &#8216;guasap&#8217;. Pero si ya estoy harto de verte la cara hijo-hija-hermano-hermana, amigo-amiga, etc \u00bf&#8217;pa&#8217; qu\u00e9 me env\u00edas fotos en las que solo se te ve a ti&#8230; Yo quiero postales. De esas que empezaban as\u00ed: \u00abEspero que al recibo de la presente est\u00e9is bien, nosotros lo estamos pasando de miedo en Zaragoza, ya hemos visto a la Virgen del Pilar&#8230;\u00bb Por supuesto, la imagen de la postal era de la Bas\u00edlica del Pilar. Lo dif\u00edcil es encontrar un buz\u00f3n para echarlas, pero haberlos, haylos&#8230; Hay que patear, pero as\u00ed veis las ciudad de que se trate al completo, ja, ja, ja.<\/p>\n<p>Si alguien quiere enviar una postal para animar a los ni\u00f1os que est\u00e1n pasando el verano encerrados por haber vulnerado la ley pod\u00e9is enviarlas al Juzgado de Menores 1, calle Marqu\u00e9s de la Ensenada, 18004, Granada. Las publicaremos en el blog.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Buenas, soy Emilio Calatayud. Acabo de llegar de la primera parte contratante de mis vacaciones y me ha dado por pensar que ya casi nadie env\u00eda postales para informar de sus veraneos. \u00a1Qu\u00e9 pena! Ya solo llegan selfies de esos a trav\u00e9s del &#8216;guasap&#8217;. Pero si ya estoy harto de verte la cara hijo-hija-hermano-hermana, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[2158,2159],"class_list":["post-8912","post","type-post","status-publish","format-standard","hentry","category-blog","tag-postales","tag-selfies"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-2jK","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/8912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=8912"}],"version-history":[{"count":3,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/8912\/revisions"}],"predecessor-version":[{"id":8916,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/8912\/revisions\/8916"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=8912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=8912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=8912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}