{"id":8124,"date":"2018-04-11T18:40:45","date_gmt":"2018-04-11T16:40:45","guid":{"rendered":"http:\/\/www.granadablogs.com\/juezcalatayud\/?p=8124"},"modified":"2018-04-11T18:40:45","modified_gmt":"2018-04-11T16:40:45","slug":"paco-lobaton-la-mayoria-de-las-desapariciones-de-menores-tienen-que-ver-con-problemas-con-el-principio-de-autoridad-y-los-estudios","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2018\/04\/paco-lobaton-la-mayoria-de-las-desapariciones-de-menores-tienen-que-ver-con-problemas-con-el-principio-de-autoridad-y-los-estudios\/","title":{"rendered":"Paco Lobat\u00f3n: \u00abLa mayor\u00eda de las desapariciones de menores tienen que ver con problemas con el principio de autoridad y los estudios\u00bb"},"content":{"rendered":"<p>&nbsp;<\/p>\n<figure id=\"attachment_8127\" aria-describedby=\"caption-attachment-8127\" style=\"width: 287px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-8127\" src=\"http:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2018\/04\/Lobat\u00f3n.jpg\" alt=\"\" width=\"287\" height=\"176\" \/><figcaption id=\"caption-attachment-8127\" class=\"wp-caption-text\">elcorreo.es<\/figcaption><\/figure>\n<p>Hola, soy Carlos Mor\u00e1n, el compa\u00f1ero de blog de don Emilio. El periodista Paco Lobat\u00f3n y el juez hablar\u00e1n ma\u00f1ana, d\u00eda 12 de abril, en Granada sobre los menores desaparecidos en una nueva edici\u00f3n de la Escuela de Padres de IDEAL que coordina el propio don Emilio. Para los que teng\u00e1is inter\u00e9s en asistir la cita es en el Teatro CajaGranada de la capital a partir de las ocho y media de la tarde. La entrada es libre hasta completar aforo.<\/p>\n<p>Aqu\u00ed os dejamos fragmentos de una entrevista que le hicimos a Paco Lobat\u00f3n hace unos d\u00edas para anunciar su participaci\u00f3n en la Escuela de Padres de IDEAL.<\/p>\n<p>&#8211;<strong>La inmensa mayor\u00eda de las desapariciones de ni\u00f1os y adolescentes terminan bien, pero esa certeza no calma a la sociedad, \u00bfpor qu\u00e9?<\/strong><\/p>\n<p>-Las desapariciones de menores tienen una resoluci\u00f3n mayoritariamente positiva. Sin embargo, trascienden los hechos m\u00e1s dram\u00e1ticos. Eso es as\u00ed. Lo normal es que acaben bien, pero siempre que se reaccione bien. Cada desaparici\u00f3n de un menor es una se\u00f1al que la sociedad debe tomarse muy en serio y responder con prontitud&#8230; Y tambi\u00e9n con mucha conciencia del riesgo, porque un menor es, por encima de otras consideraciones, una persona vulnerable.<\/p>\n<p>&#8211;<strong>\u00bfQu\u00e9 hay detr\u00e1s de esa mayor\u00eda de desapariciones de chavales que tienen un desenlace feliz?<\/strong><\/p>\n<p>-El porcentaje de bromas o de aventuras es peque\u00f1o. La mayor\u00eda tienen que ver con conflictos dentro de la familia, con problemas relacionados con el principio de autoridad y los estudios. Recientemente, una madre llam\u00f3 a &#8216;Desaparecidos&#8217; para decirnos que su hija, cuando volv\u00eda a casa con su abuela, sali\u00f3 del coche pitando, aprovechando que se hab\u00eda parado en un sem\u00e1foro. Hab\u00eda tenido malas notas y sab\u00eda que iba a tener un castigo. Entonces, se ech\u00f3 a la calle y estuvo desaparecida unos cuantos d\u00edas.<\/p>\n<p>&#8211;<strong>\u00bfQu\u00e9 lecci\u00f3n extrajo del dram\u00e1tico final del ni\u00f1o almeriense Gabriel Cruz?<\/strong><\/p>\n<p>-Para m\u00ed, lo m\u00e1s positivo es la posici\u00f3n de Patricia y \u00c1ngel, de los padres de Gabriel. La principal ense\u00f1anza es que el dolor terrible que supone que a unos padres se les arrebate un hijo de esa manera tan cruel, haya tenido una respuesta de serenidad y civismo, sin renunciar, por supuesto, a la reclamaci\u00f3n de justicia. Esa es la lecci\u00f3n principal. Pero hay otra. Despu\u00e9s del funeral, Patricia y \u00c1ngel hicieron una reflexi\u00f3n sobre c\u00f3mo la cobertura informativa lleg\u00f3 a ser tan desproporcionada que gener\u00f3 situaciones de interferencia, que es algo que tambi\u00e9n denunciaron los responsables de la investigaci\u00f3n. Este tema hay que ponerlo sobre la mesa. No se puede convertir el principio informativo de un hecho como este en una carrera desenfrenada por obtener una \u00faltima hora o una presunta exclusiva. Es que eso se hizo interfiriendo f\u00edsicamente el trabajo de los cuerpos de seguridad, que es algo que pudo tener consecuencias dram\u00e1ticas.<\/p>\n<p>&#8211;<strong>Despu\u00e9s de seguir tan de cerca estos sucesos, \u00bfc\u00f3mo digiere que se confirmen los peores presagios y los menores desaparecidos aparezcan muertos?<\/strong><\/p>\n<p>-Con dolor, con pena y con rabia. Son los tres elementos que se entrecruzan cuando se desmorona la esperanza. Pero mientras no hay evidencia de muerte, hay que mantener la esperanza de vida. Eso mantiene en pie a las familias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Hola, soy Carlos Mor\u00e1n, el compa\u00f1ero de blog de don Emilio. El periodista Paco Lobat\u00f3n y el juez hablar\u00e1n ma\u00f1ana, d\u00eda 12 de abril, en Granada sobre los menores desaparecidos en una nueva edici\u00f3n de la Escuela de Padres de IDEAL que coordina el propio don Emilio. Para los que teng\u00e1is inter\u00e9s en asistir [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[89,531,2061,90],"class_list":["post-8124","post","type-post","status-publish","format-standard","hentry","category-blog","tag-escuela","tag-ideal","tag-lobaton","tag-padres"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-272","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/8124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=8124"}],"version-history":[{"count":3,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/8124\/revisions"}],"predecessor-version":[{"id":8128,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/8124\/revisions\/8128"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=8124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=8124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=8124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}