{"id":8025,"date":"2018-03-25T10:07:03","date_gmt":"2018-03-25T08:07:03","guid":{"rendered":"http:\/\/www.granadablogs.com\/juezcalatayud\/?p=8025"},"modified":"2018-03-25T10:07:03","modified_gmt":"2018-03-25T08:07:03","slug":"vamos-a-disfrutar-de-las-procesiones-de-semana-santa-porque-igual-pronto-hay-que-hacerlas-dentro-de-las-iglesias","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2018\/03\/vamos-a-disfrutar-de-las-procesiones-de-semana-santa-porque-igual-pronto-hay-que-hacerlas-dentro-de-las-iglesias\/","title":{"rendered":"Vamos a disfrutar de las procesiones de Semana Santa, porque igual pronto hay que hacerlas dentro de las iglesias"},"content":{"rendered":"<p>&nbsp;<\/p>\n<figure id=\"attachment_3105\" aria-describedby=\"caption-attachment-3105\" style=\"width: 150px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-thumbnail wp-image-3105\" src=\"http:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2014\/04\/RP20140413-SS-MARAVILLAS-116-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><figcaption id=\"caption-attachment-3105\" class=\"wp-caption-text\">Don Emilio, a la derecha, en la procesi\u00f3n de la Sentencia de Granada.<\/figcaption><\/figure>\n<p>Buenas, soy Emilio Calatayud. Hoy vamos tempranito.Los cat\u00f3licos ya estamos en Semana Santa y los dem\u00e1s, tambi\u00e9n. Si Dios quiere, espero salir esta tarde con la &#8216;Sentencia&#8217; de Granada. A ver si el tiempo acompa\u00f1a. Vamos a disfrutar y a sentir las procesiones porque igual pronto hay que hacerlas dentro de las iglesias. Parece que va avanzando la idea de que la religi\u00f3n es algo privado y que hay que sacarla de los colegios, etc. Respeto todas las opiniones y la libertad de expresi\u00f3n, pero hay que ser consecuentes: si la religi\u00f3n cat\u00f3lica, que es la que conozco y practico, es privada, las procesiones tambi\u00e9n deber\u00edan serlo. En consecuencia, habr\u00eda que hacerlas dentro de los templos. Yo estoy dispuesto a hacerlo, a dar todas las vueltas que haga falta con los santos dentro de la iglesia.<\/p>\n<p>Por cierto, como la religi\u00f3n es algo privado, los mozos que corren los encierros no deber\u00edan encomendarse a San Ferm\u00edn en p\u00fablico&#8230; \u00bfno? \u00bfY que hacemos con las fiestas del Corpus? \u00bfY con las del Pilar?, etc.<\/p>\n<p>Esta tarde pedir\u00e9 por todos. Tambi\u00e9n por los laicos y los ateos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Buenas, soy Emilio Calatayud. Hoy vamos tempranito.Los cat\u00f3licos ya estamos en Semana Santa y los dem\u00e1s, tambi\u00e9n. Si Dios quiere, espero salir esta tarde con la &#8216;Sentencia&#8217; de Granada. A ver si el tiempo acompa\u00f1a. Vamos a disfrutar y a sentir las procesiones porque igual pronto hay que hacerlas dentro de las iglesias. Parece [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[856,857],"class_list":["post-8025","post","type-post","status-publish","format-standard","hentry","category-blog","tag-procesion","tag-sentencia"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-25r","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/8025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=8025"}],"version-history":[{"count":7,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/8025\/revisions"}],"predecessor-version":[{"id":8032,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/8025\/revisions\/8032"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=8025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=8025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=8025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}