{"id":620,"date":"2010-05-08T12:31:33","date_gmt":"2010-05-08T11:31:33","guid":{"rendered":"http:\/\/www.granadablogs.com\/juezcalatayud\/?p=620"},"modified":"2010-05-08T12:31:33","modified_gmt":"2010-05-08T11:31:33","slug":"carcel-para-una-madre-por-agredir-a-una-maestra","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2010\/05\/carcel-para-una-madre-por-agredir-a-una-maestra\/","title":{"rendered":"C\u00e1rcel para una madre por agredir a una maestra"},"content":{"rendered":"<p>Cuando todo falla, s\u00f3lo queda el Derecho Penal. Es triste tener que recurrir al \u00faltimo cartucho, pero m\u00e1s triste ser\u00eda que los agresores quedasen impunes. Aqu\u00ed os dejo una noticia sobre una condena contra una madre que agredi\u00f3 a una maestra (la hija est\u00e1 a la espera de juicio por los mismos hechos: lamentable). Es de mi compa\u00f1ero Jos\u00e9 Ram\u00f3n Villalba:<\/p>\n<p><span id=\"form-articulo-top\" class=\"contenido_form_articulo\"> <\/span><\/p>\n<div class=\"colABC_articulo\">\n<div class=\"colAB_articulo\">\n<div class=\"colAB_articulo\">\n<div class=\"text\">\n<div id=\"story-texto\" class=\"p\">\n<div class=\"p\">\u00abUna profesora de un IES de \u00cdllora ha conseguido una \u00abpeque\u00f1a victoria\u00bb, seg\u00fan ella, para \u00abque los agresores se lo piensen dos veces antes de actuar\u00bb. La jefa de estudios del IES Diego de Silo\u00e9 de \u00cdllora se mostr\u00f3 satisfecha al conocer una sentencia del titular del juzgado de lo penal n\u00famero 4 de Granada que condena a seis meses de c\u00e1rcel y multa de 120 euros a Palmira H.H. por la agresi\u00f3n dirigida a la profesora.<\/div>\n<div class=\"p\">El pasado 6 de mayo 2009, la madre de un alumno de dicha profesora la abord\u00f3 y le solt\u00f3 lindezas del tipo: \u00abestoy hasta el co\u00f1o de ser llamada al colegio, aqu\u00ed te podemos hacer poco, pero en la calle te esperamos\u00bb. Seg\u00fan la sentencia dictada por el juzgado, la agresora se lanz\u00f3 a la mand\u00edbula de la jefa de estudios y la zarande\u00f3 bajo amenazas de que \u00e9sta no denunciara a la Guardia Civil o lo pagar\u00eda. Cuando se produjo la agresi\u00f3n, tambi\u00e9n estaba presente una menor que acompa\u00f1aba a la agresora y que aprovech\u00f3 para abofetear a la profesora\u00bb.<\/div>\n<div class=\"p\">M\u00e1s informaci\u00f3n IDEAL o www.ideal.es<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cuando todo falla, s\u00f3lo queda el Derecho Penal. Es triste tener que recurrir al \u00faltimo cartucho, pero m\u00e1s triste ser\u00eda que los agresores quedasen impunes. Aqu\u00ed os dejo una noticia sobre una condena contra una madre que agredi\u00f3 a una maestra (la hija est\u00e1 a la espera de juicio por los mismos hechos: lamentable). Es [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-620","post","type-post","status-publish","format-standard","hentry","category-blog"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-a0","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=620"}],"version-history":[{"count":3,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/620\/revisions"}],"predecessor-version":[{"id":623,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/620\/revisions\/623"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}