{"id":610,"date":"2010-04-28T16:57:25","date_gmt":"2010-04-28T15:57:25","guid":{"rendered":"http:\/\/www.granadablogs.com\/juezcalatayud\/?p=610"},"modified":"2010-04-28T16:57:25","modified_gmt":"2010-04-28T15:57:25","slug":"el-derecho-a-borrar-tu-huella-de-internet-sobre-todo-los-menores","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2010\/04\/el-derecho-a-borrar-tu-huella-de-internet-sobre-todo-los-menores\/","title":{"rendered":"El derecho a borrar tu huella de Internet (sobre todo, los menores)"},"content":{"rendered":"<p>\u00a0<\/p>\n<p>Que las cosas no pueden seguir como est\u00e1n actualmente en Internet es algo que ya muy pocos discuten. Ma\u00f1ana comienza en Madrid un encuentro que defiende la necesidad de que tengamos derecho -y, sobre todo, los menores- a borrar nuestro paso por Internet cuando lo deseemos. Buena idea. Os dejo la noticia.<\/p>\n<p>\u00abEl derecho a la privacidad, al &#8216;olvido&#8217; en Internet y la protecci\u00f3n de la infancia ser\u00e1n temas centrales de la tercera edici\u00f3n del Di\u00e1logo Europeo sobre la Gobernanza de Internet (EuroDIG), que comienza ma\u00f1ana en Madrid.<\/p>\n<p class=\"resumeArcticle\" style=\"font-size: 13px;\">En un encuentro informativo, el coordinador del Foro de la Gobernanza de Internet en Espa\u00f1a, Jorge P\u00e9rez, destac\u00f3 c\u00f3mo los temas t\u00e9cnicos est\u00e1n dejando de ser el centro del debate de Internet, que cada vez se ocupa m\u00e1s de la privacidad y sobre todo del uso que los ni\u00f1os hacen de la red.<\/p>\n<p class=\"resumeArcticle\" style=\"font-size: 13px;\">Explic\u00f3 que las empresas e instituciones buscan en la red el perfil de las personas que van a contratar, por lo que las \u00abtonter\u00edas\u00bb que dejan los ni\u00f1os y j\u00f3venes en Internet pueden condicionar su futuro laboral.<\/p>\n<p class=\"resumeArcticle\" style=\"font-size: 13px;\">Por eso, dijo, se habla ya del derecho, sobre todo de los menores, a borrar su huella en Internet.<\/p>\n<p class=\"resumeArcticle\" style=\"font-size: 13px;\">La conferencia EuroDIG, que ma\u00f1ana celebra su tercer encuentro, es un foro de debate abierto en el que representantes de los 47 pa\u00edses europeos abordar\u00e1n las cuestiones que m\u00e1s preocupan de la red\u00bb.<\/p>\n<p class=\"resumeArcticle\" style=\"font-size: 13px;\">\u00a0<\/p>\n<p class=\"resumeArcticle\" style=\"font-size: 13px;\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 Que las cosas no pueden seguir como est\u00e1n actualmente en Internet es algo que ya muy pocos discuten. Ma\u00f1ana comienza en Madrid un encuentro que defiende la necesidad de que tengamos derecho -y, sobre todo, los menores- a borrar nuestro paso por Internet cuando lo deseemos. Buena idea. Os dejo la noticia. \u00abEl derecho [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-610","post","type-post","status-publish","format-standard","hentry","category-blog"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-9Q","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=610"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/610\/revisions"}],"predecessor-version":[{"id":611,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/610\/revisions\/611"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}