{"id":5346,"date":"2016-11-09T21:05:40","date_gmt":"2016-11-09T19:05:40","guid":{"rendered":"http:\/\/www.granadablogs.com\/juezcalatayud\/?p=5346"},"modified":"2016-11-09T21:05:40","modified_gmt":"2016-11-09T19:05:40","slug":"no-es-normal-pasarle-la-pension-de-alimentos-a-un-nino-de-33-anos-casado-y-con-trabajo","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2016\/11\/no-es-normal-pasarle-la-pension-de-alimentos-a-un-nino-de-33-anos-casado-y-con-trabajo\/","title":{"rendered":"No es normal pasarle la pensi\u00f3n de alimentos a un &#8216;ni\u00f1o&#8217; de 33 a\u00f1os, casado y con trabajo"},"content":{"rendered":"<p>Buenas, soy Emilio Calatayud. Una persona me ha hecho la siguiente pregunta: \u00ab\u00bfEs normal que el hijo de un matrimonio divorciado con un hijo de 33 a\u00f1os casado trabajando siga recibiendo la pensi\u00f3n de alimentos?\u00bb. Respuesta: pues no, no es normal. Yo creo que ya va siendo hora que le quiten la pensi\u00f3n de alimentos, sobre todo, porque no le hace falta. Que los padres guarden el dinero para tener una jubilaci\u00f3n lo m\u00e1s c\u00f3moda posible. Lo otro es malcriar al ni\u00f1o. Y si el &#8216;ni\u00f1o&#8217; se queja, que vaya al juzgado y presente una demanda. Y a ver qu\u00e9 dice la justicia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buenas, soy Emilio Calatayud. Una persona me ha hecho la siguiente pregunta: \u00ab\u00bfEs normal que el hijo de un matrimonio divorciado con un hijo de 33 a\u00f1os casado trabajando siga recibiendo la pensi\u00f3n de alimentos?\u00bb. Respuesta: pues no, no es normal. Yo creo que ya va siendo hora que le quiten la pensi\u00f3n de alimentos, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[1171,1030],"class_list":["post-5346","post","type-post","status-publish","format-standard","hentry","category-blog","tag-alimentos","tag-pension"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-1oe","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/5346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=5346"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/5346\/revisions"}],"predecessor-version":[{"id":5351,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/5346\/revisions\/5351"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=5346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=5346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=5346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}