{"id":479,"date":"2010-01-22T19:31:01","date_gmt":"2010-01-22T18:31:01","guid":{"rendered":"http:\/\/www.granadablogs.com\/juezcalatayud\/?p=479"},"modified":"2010-01-22T19:31:01","modified_gmt":"2010-01-22T18:31:01","slug":"haiti-y-ademas-trafico-de-menores","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2010\/01\/haiti-y-ademas-trafico-de-menores\/","title":{"rendered":"Hait\u00ed: Y, adem\u00e1s, tr\u00e1fico de menores"},"content":{"rendered":"<p class=\"resumeArcticle\" style=\"font-size: 13px;\">Por si no fuera poco lo que ya tienen encima, en Hait\u00ed siguen activas las redes de hienas humanas que se dedican a robar ni\u00f1os para venderlos al mejor postor. Es una situaci\u00f3n diab\u00f3lica: el Centro Internacional de Referencia para los Derechos del Ni\u00f1o Privado de Familia (CIR)\u00a0establece que la adopci\u00f3n internacional no puede tener lugar en una situaci\u00f3n de guerra o de cat\u00e1strofe natural, lo cual es l\u00f3gico. As\u00ed que los peque\u00f1os deben quedarse all\u00ed, rodeados de peligros. Peor imposible.<\/p>\n<p class=\"resumeArcticle\" style=\"font-size: 13px;\">Unicef ya ha dado la voz de alarma. \u00abUnicef denunci\u00f3 hoy el rapto de al menos 15 ni\u00f1os no acompa\u00f1ados en hospitales de Hait\u00ed. \u00abLamentablemente hemos constatado el rapto de 15 ni\u00f1os en diferentes hospitales de Hait\u00ed y sospechamos que han sido secuestrados por redes de trata a trav\u00e9s de Santo Domingo\u00bb, afirm\u00f3 en rueda de prensa Jean Claude Legrand, asesor de protecci\u00f3n de la infancia de Unicef. Preguntado sobre dichos raptos y la posibilidad de que se hayan producido m\u00e1s, el funcionario internacional matiz\u00f3 que hasta la fecha tienen \u00abevidencia\u00bb de esos casos, pero que preocupa que el fen\u00f3meno se extienda.<\/p>\n<p class=\"resumeArcticle\" style=\"font-size: 13px;\">Legrand explic\u00f3 que las redes de trata de menores exist\u00edan antes del terremoto. \u00abLas redes exist\u00edan previamente en Hait\u00ed y eran bastante activas, raptando ni\u00f1os y entreg\u00e1ndolos al mercado internacional de adopciones. Lo que ocurre siempre es que cuando hay una cat\u00e1strofe, las redes tratan de aprovecharse de la fragilidad del Estado y de los sistemas de control\u00bb, explic\u00f3 Legrand.\u00a0 Por ello, Unicef ha establecido todos los mecanismos de alerta disponibles para evitar que estos secuestros se produzcan, y est\u00e1 organizando el establecimiento de campos de acogida para albergar a todos los ni\u00f1os no acompa\u00f1ados.Legrand puso \u00e9nfasis en destacar que dichos menores \u00abno son hu\u00e9rfanos\u00bb.Es necesario comprobar fehacientemente que no tienen ninguno de los dos progenitores, seg\u00fan Legrand que a\u00f1adi\u00f3: \u00abde todas formas en Hait\u00ed la familia es extensa y estoy seguro de que habr\u00e1 familiares de esos ni\u00f1os que querr\u00e1n adoptarlos\u00bb.<\/p>\n<p class=\"resumeArcticle\" style=\"font-size: 13px;\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por si no fuera poco lo que ya tienen encima, en Hait\u00ed siguen activas las redes de hienas humanas que se dedican a robar ni\u00f1os para venderlos al mejor postor. Es una situaci\u00f3n diab\u00f3lica: el Centro Internacional de Referencia para los Derechos del Ni\u00f1o Privado de Familia (CIR)\u00a0establece que la adopci\u00f3n internacional no puede tener [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-479","post","type-post","status-publish","format-standard","hentry","category-blog"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-7J","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=479"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/479\/revisions"}],"predecessor-version":[{"id":480,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/479\/revisions\/480"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}