{"id":4724,"date":"2016-05-03T20:31:50","date_gmt":"2016-05-03T18:31:50","guid":{"rendered":"http:\/\/www.granadablogs.com\/juezcalatayud\/?p=4724"},"modified":"2016-05-03T20:31:50","modified_gmt":"2016-05-03T18:31:50","slug":"los-politicos-de-la-transicion-tenian-mas-razones-para-odiarse-que-los-de-ahora-y-llegaron-a-acuerdos","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2016\/05\/los-politicos-de-la-transicion-tenian-mas-razones-para-odiarse-que-los-de-ahora-y-llegaron-a-acuerdos\/","title":{"rendered":"Los pol\u00edticos de la Transici\u00f3n ten\u00edan m\u00e1s razones para odiarse que los de ahora y llegaron a acuerdos"},"content":{"rendered":"<p>Buenas, soy Emilio Calatayud. El pr\u00f3ximo 26 de junio, a votar de nuevo y nada parece haber cambiado. Como cuando \u00edbamos al colegio, este no se &#8216;ajunta&#8217; con aquel y el de m\u00e1s all\u00e1 no se habla con el de m\u00e1s ac\u00e1, etc. Los pol\u00edticos de la Transici\u00f3n ten\u00edan m\u00e1s razones para odiarse -las heridas estaban m\u00e1s frescas- y, sin embargo, llegaron a acuerdos que fueron buenos para todos. Pero los de ahora ni siquiera quieren verse ni escucharse. \u00bfQu\u00e9 nos ha pasado? \u00bfQu\u00e9 nos est\u00e1 pasando? \u00bfPor qu\u00e9 esas distancias que parecen abismos?<\/p>\n<p>Creo que ya lo he dicho alguna vez: me temo que todo esto se debe a que no hemos sido capaces de hacer una ley de Educaci\u00f3n que dure 30 a\u00f1os y unos pol\u00edticos son de la EGB, otros de la Logse, otros de la Lomce&#8230; y, claro, no se entienden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buenas, soy Emilio Calatayud. El pr\u00f3ximo 26 de junio, a votar de nuevo y nada parece haber cambiado. Como cuando \u00edbamos al colegio, este no se &#8216;ajunta&#8217; con aquel y el de m\u00e1s all\u00e1 no se habla con el de m\u00e1s ac\u00e1, etc. Los pol\u00edticos de la Transici\u00f3n ten\u00edan m\u00e1s razones para odiarse -las heridas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[793,1428],"class_list":["post-4724","post","type-post","status-publish","format-standard","hentry","category-blog","tag-elecciones","tag-nuevas"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-1ec","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/4724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=4724"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/4724\/revisions"}],"predecessor-version":[{"id":4725,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/4724\/revisions\/4725"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=4724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=4724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=4724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}