{"id":4009,"date":"2015-08-19T20:50:43","date_gmt":"2015-08-19T18:50:43","guid":{"rendered":"http:\/\/www.granadablogs.com\/juezcalatayud\/?p=4009"},"modified":"2015-08-19T20:50:43","modified_gmt":"2015-08-19T18:50:43","slug":"escalera-hacia-el-cielo-de-los-bomberos-en-granada","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2015\/08\/escalera-hacia-el-cielo-de-los-bomberos-en-granada\/","title":{"rendered":"Escalera hacia el cielo de los bomberos en Granada"},"content":{"rendered":"<p>Buenas, soy Emilio Calatayud. Este pr\u00f3ximo viernes 21 de agosto, a partir de las seis de la tarde, la cima de Granada, Sierra Nevada, va a acoger una prueba muy especial: un mont\u00f3n de bomberos van a competir en una carrera de subir escaleras. La previsi\u00f3n es que asciendan unos 600 pelda\u00f1os cargados con todo su equipo. A poco que\u00a0se despisten, y teniendo en cuenta que van a estar a casi tres mil metros de altitud, lo mismo tocan el cielo, que en esta parte de Granada est\u00e1 muy, muy cerca. Os lo cuento para que, si est\u00e1is de vacaciones -lo mismo da que se\u00e1is granadinos que de fuera-, os sub\u00e1is a la estaci\u00f3n invernal de Sierra Nevada para asistir a esta competici\u00f3n, que no se ve todos los d\u00edas. Yo estar\u00e9. Los bomberos de Granada me han pedido que les acompa\u00f1e y he aceptado encantado. En otras ocasiones son ellos los que me han echado una mano a m\u00ed y a la justicia en general. Por ejemplo, colaborando en el cumplimiento de las medidas de algunos de &#8216;mis choricillos&#8217;\u00a0. Animaros, que en la Sierra se est\u00e1 muy fresquito y se cr\u00edan gl\u00f3bulos rojos, que son muy buenos para el cerebro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buenas, soy Emilio Calatayud. Este pr\u00f3ximo viernes 21 de agosto, a partir de las seis de la tarde, la cima de Granada, Sierra Nevada, va a acoger una prueba muy especial: un mont\u00f3n de bomberos van a competir en una carrera de subir escaleras. La previsi\u00f3n es que asciendan unos 600 pelda\u00f1os cargados con todo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[1174,1175,529],"class_list":["post-4009","post","type-post","status-publish","format-standard","hentry","category-blog","tag-bomberos","tag-carrera","tag-sierra-nevada"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-12F","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/4009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=4009"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/4009\/revisions"}],"predecessor-version":[{"id":4010,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/4009\/revisions\/4010"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=4009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=4009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=4009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}