{"id":3947,"date":"2015-07-21T23:09:22","date_gmt":"2015-07-21T21:09:22","guid":{"rendered":"http:\/\/www.granadablogs.com\/juezcalatayud\/?p=3947"},"modified":"2015-07-21T23:09:22","modified_gmt":"2015-07-21T21:09:22","slug":"parece-que-hemos-vuelto-a-mayo-del-68-con-el-consumo-de-marihuana-cuando-fumarse-un-porro-era-de-intelectuales","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2015\/07\/parece-que-hemos-vuelto-a-mayo-del-68-con-el-consumo-de-marihuana-cuando-fumarse-un-porro-era-de-intelectuales\/","title":{"rendered":"\u00abParece que hemos vuelto a mayo del 68 con el consumo de marihuana, cuando fumarse un porro era de intelectuales\u00bb"},"content":{"rendered":"<p>Hola, soy Carlos Mor\u00e1n, el compa\u00f1ero de blog de don Emilio. Tal y como os anunciamos en un comentario anterior, el juez est\u00e1 dirigiendo un curso sobre &#8216;Adicciones en Internet en la localidad almeriense de Purchena. Aqu\u00ed os dejamos algunas de las cosas que ha dicho en la inauguraci\u00f3n de las jornadas. La informaci\u00f3n es de la agencia Efe.<\/p>\n<p>\u00abEl juez de Menores de Granada Emilio Calatayud ha advertido este martes de que los tel\u00e9fonos m\u00f3viles son \u00abun instrumento id\u00f3neo para cometer los delitos de la clase media y media-alta como son acosos, amenazas e injurias contra el honor y la intimidad\u00bb.<\/p>\n<p>Calatayud ha hecho esta reflexi\u00f3n en el marco de la conferencia inaugural del curso de verano de la UAL sobre &#8216;Adicciones en Menores&#8217; que \u00e9l dirige y ha dado comienzo en Purchena (Almer\u00eda).<\/p>\n<p>\u00abLas nuevas tecnolog\u00edas ya son una droga, especialmente los m\u00f3viles, que generan verdaderos s\u00edndromes de abstinencia\u00bb, ha indicado para se\u00f1alar que al sistema llegan \u00abmuchos chavales detenidos por maltrato pero no son maltratadores sino que se les ha castigado sin el uso de estas tecnolog\u00edas\u00bb.<\/p>\n<p>Calatayud tambi\u00e9n ha alertado sobre el consumo de alcohol en menores y ha asegurado que es la \u00abpuerta de la drogadicci\u00f3n\u00bb. \u00abPor eso soy contrario a las fiestas porque son botellones institucionalizados. Esta es la hipocres\u00eda social porque los menores empiezan a consumir con 12 y 13 a\u00f1os y poco se hace para evitarlo\u00bb, ha apuntillado.<\/p>\n<p>Al hilo de esto, ha considerado que el ambiente actual hace que parezca que \u00abhayamos vuelto a mayo del 68 con respecto al consumo de marihuana cuando fumarse un porro era de intelectuales\u00bb. \u00abYo siempre digo que cuando entr\u00e9 de juez, en el 80, un drogata no duraba 15 a\u00f1os porque era la \u00e9poca de la hero\u00edna y mor\u00edan por el Sida. Ahora no mueren, pero como empiezan a muy temprana edad, a los 19 a\u00f1os hay muchos j\u00f3venes que tienen problemas mentales\u00bb, ha a\u00f1adido.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hola, soy Carlos Mor\u00e1n, el compa\u00f1ero de blog de don Emilio. Tal y como os anunciamos en un comentario anterior, el juez est\u00e1 dirigiendo un curso sobre &#8216;Adicciones en Internet en la localidad almeriense de Purchena. Aqu\u00ed os dejamos algunas de las cosas que ha dicho en la inauguraci\u00f3n de las jornadas. La informaci\u00f3n es [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[1138,5,774],"class_list":["post-3947","post","type-post","status-publish","format-standard","hentry","category-blog","tag-curso","tag-menores","tag-purchena"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-11F","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/3947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=3947"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/3947\/revisions"}],"predecessor-version":[{"id":3949,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/3947\/revisions\/3949"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=3947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=3947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=3947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}