{"id":3945,"date":"2015-07-23T21:47:38","date_gmt":"2015-07-23T19:47:38","guid":{"rendered":"http:\/\/www.granadablogs.com\/juezcalatayud\/?p=3945"},"modified":"2015-07-23T21:47:38","modified_gmt":"2015-07-23T19:47:38","slug":"los-casos-de-violencia-de-hijos-a-padres-han-aumentado-un-60-en-andalucia-en-cinco-anos","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2015\/07\/los-casos-de-violencia-de-hijos-a-padres-han-aumentado-un-60-en-andalucia-en-cinco-anos\/","title":{"rendered":"Los casos de violencia de hijos a padres han aumentado un 60% en Andaluc\u00eda en cinco a\u00f1os"},"content":{"rendered":"<p>Buenas, soy Emilio Calatayud. En cinco a\u00f1os, y seg\u00fan los datos elaborados por el Denfenso del Menor, los casos de agresiones de padres a hijos han aumentado un 60% en Andaluc\u00eda, que es una aut\u00e9ntica barbaridad. Pero para los fiscales y jueces de Menores no ha sido ninguna sorpresa. Lo ven\u00edamos avisando desde hace varios a\u00f1os. Desgraciadamente, no nos hemos equivocado. Lo bueno es que cada vez son m\u00e1s las instituciones que est\u00e1n tomando conciencia de la magnitud del problema, que es la mejor forma de encontrar las soluciones. Seguro que ma\u00f1ana estaremos mejor que hoy.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buenas, soy Emilio Calatayud. En cinco a\u00f1os, y seg\u00fan los datos elaborados por el Denfenso del Menor, los casos de agresiones de padres a hijos han aumentado un 60% en Andaluc\u00eda, que es una aut\u00e9ntica barbaridad. Pero para los fiscales y jueces de Menores no ha sido ninguna sorpresa. Lo ven\u00edamos avisando desde hace varios [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[189,90,186],"class_list":["post-3945","post","type-post","status-publish","format-standard","hentry","category-blog","tag-hijos","tag-padres","tag-violencia"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-11D","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/3945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=3945"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/3945\/revisions"}],"predecessor-version":[{"id":3954,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/3945\/revisions\/3954"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=3945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=3945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=3945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}