{"id":3201,"date":"2014-06-12T20:45:12","date_gmt":"2014-06-12T19:45:12","guid":{"rendered":"http:\/\/www.granadablogs.com\/juezcalatayud\/?p=3201"},"modified":"2014-06-12T20:45:12","modified_gmt":"2014-06-12T19:45:12","slug":"comienza-el-mundial-los-ninos-y-la-crisis","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2014\/06\/comienza-el-mundial-los-ninos-y-la-crisis\/","title":{"rendered":"Comienza el Mundial: los ni\u00f1os y la crisis"},"content":{"rendered":"<p>Empieza el Mundial de F\u00fatbol. A ver si vemos juego bonito y, sobre todo, limpio, que hay miles de chavales pendientes y no podemos darles malos ejemplos. Pero s\u00ed buenos: me encanta la idea de Elena Alfaro de invitar a los nuestros a que echen una mano con sus primas por ganar\u00a0a los ni\u00f1os que lo est\u00e1n pasando mal en Espa\u00f1a por culpa de la crisis.A ver si se consigue. Ganar\u00edamos el Mundial por partida doble.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Empieza el Mundial de F\u00fatbol. A ver si vemos juego bonito y, sobre todo, limpio, que hay miles de chavales pendientes y no podemos darles malos ejemplos. Pero s\u00ed buenos: me encanta la idea de Elena Alfaro de invitar a los nuestros a que echen una mano con sus primas por ganar\u00a0a los ni\u00f1os que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[878,877,41],"class_list":["post-3201","post","type-post","status-publish","format-standard","hentry","category-blog","tag-futbol","tag-mundial","tag-ninos"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-PD","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/3201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=3201"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/3201\/revisions"}],"predecessor-version":[{"id":3202,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/3201\/revisions\/3202"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=3201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=3201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=3201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}