{"id":3073,"date":"2014-03-30T15:02:47","date_gmt":"2014-03-30T14:02:47","guid":{"rendered":"http:\/\/www.granadablogs.com\/juezcalatayud\/?p=3073"},"modified":"2014-03-30T15:02:47","modified_gmt":"2014-03-30T14:02:47","slug":"mis-hijos-no-han-pasado-por-un-juzgado-pero-podrian-haber-pasado","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2014\/03\/mis-hijos-no-han-pasado-por-un-juzgado-pero-podrian-haber-pasado\/","title":{"rendered":"\u00abMis hijos no han pasado por un juzgado, pero podr\u00edan haber pasado\u00bb"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Hace ya algunos d\u00edas, los diarios del Grupo Joly publicaron una entrevista con motivo de la publicaci\u00f3n del nuevo libro de don Emilio, &#8216;Buenas, soy Emilio Calatayud y voy a hablarles&#8230;&#8217; (editorial Alienta-Planeta). \u00a0Aqu\u00ed os dejamos un fragmento de esa charla. El juez dice, entre otras cosas, que sus dos hijos no han tenido encontronazos con la justicia, pero admite que podr\u00edan haberlos tenido. O sea, que su familia es como cualquier otra. Nadie est\u00e1 libre de tener problemas con la descendencia. La &#8216;preguntadora&#8217; es la periodista del peri\u00f3dico Granada Hoy Yenalia Huertas, una buena amiga y una excelente profesional. Esperamos que sea de vuestro inter\u00e9s.<\/p>\n<p><strong>-\u00bfQu\u00e9 se va a encontrar el lector en sus p\u00e1ginas que no haya le\u00eddo antes?<\/strong><\/p>\n<p>-Una parte muy personal, pues entend\u00edamos que el nuevo lector no tiene por qu\u00e9 conocer al personaje, al juez que habla en los anteriores. En esa parte cuento la enfermedad de mi mujer; su fallecimiento; el tiempo, como se suele decir, de luto; y el volver a reiniciarse despu\u00e9s de una \u00e9poca muy dura. Luego ya actualizo la problem\u00e1tica que vivo en el juzgado todos los d\u00edas y a\u00f1ado opiniones sobre la situaci\u00f3n actual del pa\u00eds, la pol\u00edtica o la crisis. Es un libro fundamentalmente dirigido a los padres.<\/p>\n<p><strong>-\u00bfPor qu\u00e9 hacer p\u00fablico el c\u00e1ncer de su mujer?<\/strong><\/p>\n<p>-A m\u00ed me ha servido mucho porque es una especie de terapia. He estado 32 a\u00f1os con mi mujer (30 a\u00f1os y medio casado y otros dos o tres de novietes; o sea, toda mi vida) y me ha venido bien soltar lo que he sentido en esos momentos. No s\u00f3lo lo he hecho por los dem\u00e1s, sino por m\u00ed, porque expresar lo que sientes te ayuda un poco a pasar p\u00e1gina. La vida sigue y hay que tirar para adelante.<\/p>\n<p><strong>-Tiene dos hijos.<\/strong><\/p>\n<p>-S\u00ed, tengo dos.<\/p>\n<p><strong>-\u00bfY le han dado alg\u00fan problema?<\/strong><\/p>\n<p>-\u00a1Claro! \u00a1Y me siguen dando! Ya sabe eso de que los problemas de los hijos te los quitas cuando te mueres. Pero, vamos, son buenos chicos, no me quejo. Nos hemos ayudado mutuamente en este tiempo&#8230; Ha sido una forma m\u00e1s de ver que la familia est\u00e1 unida.<\/p>\n<p><strong>-\u00bfPasar por el juzgado no habr\u00e1n pasado?<\/strong><\/p>\n<p>-\u00a1No! Pero pod\u00edan haber pasado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Hace ya algunos d\u00edas, los diarios del Grupo Joly publicaron una entrevista con motivo de la publicaci\u00f3n del nuevo libro de don Emilio, &#8216;Buenas, soy Emilio Calatayud y voy a hablarles&#8230;&#8217; (editorial Alienta-Planeta). \u00a0Aqu\u00ed os dejamos un fragmento de esa charla. El juez dice, entre otras cosas, que sus dos hijos no han tenido [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[189,284,849],"class_list":["post-3073","post","type-post","status-publish","format-standard","hentry","category-blog","tag-hijos","tag-juzgado","tag-juzgados"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-Nz","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/3073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=3073"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/3073\/revisions"}],"predecessor-version":[{"id":3074,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/3073\/revisions\/3074"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=3073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=3073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=3073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}