{"id":2215,"date":"2012-12-19T18:24:44","date_gmt":"2012-12-19T17:24:44","guid":{"rendered":"http:\/\/www.granadablogs.com\/juezcalatayud\/?p=2215"},"modified":"2012-12-19T18:25:38","modified_gmt":"2012-12-19T17:25:38","slug":"la-audiencia-de-granada-obliga-a-dos-maestros-a-escolarizar-a-su-hijo","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2012\/12\/la-audiencia-de-granada-obliga-a-dos-maestros-a-escolarizar-a-su-hijo\/","title":{"rendered":"La Audiencia de Granada obliga a dos maestros a escolarizar a su hijo"},"content":{"rendered":"<p>En un auto salom\u00f3nico, la Audiencia Provincial de Granada ha resuelto que una pareja de maestros que sac\u00f3 a su hijo del colegio para darle las clases en casa -una pr\u00e1ctica conocida como &#8216;homeschooling&#8217;- debe devolverlo a las aulas, pero el tribunal tambi\u00e9n concluye que la conducta de los docentes no es delictiva.<\/p>\n<div id=\"noticia-pestanas\">\n<div id=\"ccronica\">\n<div>\n<div id=\"story-texto\">\n<div>La Fiscal\u00eda hab\u00eda denunciado a los profesores &#8216;disidentes&#8217;, que residen en la Costa, por entender que podr\u00edan estar cometiendo un presunto delito de abandono de familia, pero la Audiencia no lo ha visto as\u00ed&#8230; Aunque, eso s\u00ed, insiste en que el chaval tiene que ir a &#8216;cole&#8217;.<\/div>\n<div>En este sentido, los magistrados granadinos invocan una sentencia del Tribunal Constitucional y otra dictada recientemente por la Audiencia de Alicante que defienden que el legislador ha optado \u00abpor una ense\u00f1anza b\u00e1sica obligatoria\u00bb que ha de impartirse \u00aben centros educativos presenciales\u00bb. Luego el &#8216;homeschooling&#8217; no tiene cabida en Espa\u00f1a. \u00abMal que le pese a los padres del menor -reproduce la Audiencia de Granada lo que dijo la de Alicante-, est\u00e1n viviendo en la sociedad espa\u00f1ola y deben cumplir con la Constituci\u00f3n y las leyes, y entre estas leyes se encuentra la legislaci\u00f3n sobre educaci\u00f3n de sus hijos, que les obliga a escolarizarlos en un centro, (&#8230;) que evidentemente puede ser por ellos elegido, pero de los reconocidos por la administraci\u00f3n competente\u00bb.<\/div>\n<div>La resoluci\u00f3n tambi\u00e9n advierte de que la \u00abpotestad\u00bb que tienen los padres de dar a sus hijos una formaci\u00f3n \u00abintegral\u00bb no significa que puedan instruirlos \u00aba su libre albedr\u00edo\u00bb, esto es, como les d\u00e9 la gana. \u00abNo pueden atribuirse unos derechos que corresponden a los hijos y no a las padres, como es el derecho a la educaci\u00f3n\u00bb.<\/div>\n<div>El auto del tribunal granadino, citando de nuevo a la Audiencia de Alicante, concluye que, \u00abaunque el menor no se encuentra en situaci\u00f3n de abandono o aislamiento que implique una perturbaci\u00f3n da\u00f1osa a pesar de no acudir al centro escolar\u00bb, s\u00ed existe \u00abuna situaci\u00f3n de peligro o perjudicial\u00bb para el muchacho. As\u00ed que insta al ministerio fiscal a que prosiga con \u00absus acciones en la v\u00eda civil (&#8230;), a fin de que se proceda a la escolarizaci\u00f3n\u00bb del joven en un centro oficial.<\/div>\n<div>El asunto se judicializ\u00f3 despu\u00e9s de el colegio en el que estaba matriculado el chico y el Ayuntamiento de la localidad en la que reside la familia elaborasen sendos informes en los que detallaban que el menor hab\u00eda dejado de asistir a clase en abril de 2010 y, un a\u00f1o despu\u00e9s, no hab\u00eda regresados a las aulas. Se dio de baja por decisi\u00f3n de sus padres, que estimaban que el hogar \u00abofrece un contexto educativo m\u00e1s adecuado y personalizado\u00bb que el \u00absistema\u00bb reglado.<\/div>\n<div>En opini\u00f3n de los progenitores del chaval, la escuela tradicional \u00abbloquea el inter\u00e9s del ni\u00f1o\u00bb y su \u00abausencia de escolarizaci\u00f3n (&#8230;) no afecta a su socializaci\u00f3n\u00bb.<\/div>\n<div>Sin embargo, la Audiencia no ha compartido esos argumentos, pero tambi\u00e9n es cierto que no ha apreciado la existencia de un delito. \u00abAunque el menor no est\u00e1 escolarizado oficialmente, s\u00ed est\u00e1 recibiendo una educaci\u00f3n integral por sus padres, que, adem\u00e1s, son profesores de educaci\u00f3n general b\u00e1sica, maestros de escuela, lo que no constituye infracci\u00f3n penal (&#8230;), entendiendo que la no asistencia a un centro educativo oficial, en estos casos en los que s\u00ed se est\u00e1 educando (&#8230;), contraviene normas de car\u00e1cter administrativo, pero no penal\u00bb, razona el tribunal granadino.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>En un auto salom\u00f3nico, la Audiencia Provincial de Granada ha resuelto que una pareja de maestros que sac\u00f3 a su hijo del colegio para darle las clases en casa -una pr\u00e1ctica conocida como &#8216;homeschooling&#8217;- debe devolverlo a las aulas, pero el tribunal tambi\u00e9n concluye que la conducta de los docentes no es delictiva. La Fiscal\u00eda [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[291],"class_list":["post-2215","post","type-post","status-publish","format-standard","hentry","category-blog","tag-homeschooling"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-zJ","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/2215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=2215"}],"version-history":[{"count":4,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/2215\/revisions"}],"predecessor-version":[{"id":2219,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/2215\/revisions\/2219"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=2215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=2215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=2215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}