{"id":2198,"date":"2012-12-13T00:01:50","date_gmt":"2012-12-12T23:01:50","guid":{"rendered":"http:\/\/www.granadablogs.com\/juezcalatayud\/?p=2198"},"modified":"2012-12-13T00:12:16","modified_gmt":"2012-12-12T23:12:16","slug":"pedro-garcia-aguado-el-hermano-mayor-nosotros-tenemos-que-educar-a-nuestros-hijos-ninguna-autoridad-ni-institucion-puede-hacerlo-por-nosotros","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2012\/12\/pedro-garcia-aguado-el-hermano-mayor-nosotros-tenemos-que-educar-a-nuestros-hijos-ninguna-autoridad-ni-institucion-puede-hacerlo-por-nosotros\/","title":{"rendered":"Pedro Garc\u00eda Aguado, el &#8216;Hermano mayor&#8217;: \u00abNosotros tenemos que educar a nuestros hijos, ninguna autoridad ni instituci\u00f3n puede hacerlo por nosotros\u00bb"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>Hace unas horas he conversado por tel\u00e9fono con Pedro Garc\u00eda Aguado, el &#8216;Hermano mayor&#8217; de la &#8216;tele&#8217;, que hoy d\u00eda 13 va a estar en Granada junto a Don Emilio. Ha sido un di\u00e1logo largo e interesante, pero me quedo con esta verdad que alguno dir\u00e1 que es de perogrullo, pero no por eso deja de ser una gran verdad. \u00abLos padres no podemos escaquearnos de nuestras responsabilidades y confiar en que sean las autoridades y las instituciones las que eduquen a nuestros hijos. Son nuestros hijos y tenemos que educarlos nosotros. A los seis o siete a\u00f1os tenemos que empezar a entrenarlos para que adopten la decisi\u00f3n correcta cuando tengan catorce o quince, para que digan \u2018no\u2019 al alcohol y las drogas cuando lleguen a esas edades cr\u00edticas. Luego, cuando cumplan los 18, que hagan lo que quieran. Pero hasta entonces, son nuestra responsabilidad\u00bb.<\/p>\n<p>Pedro y don Emilio estar\u00e1n hoy en el Museo de CajaGranada a partir de las siete y media de la tarde. Son los encargados de inaugurar la Escuela de Padres de IDEAL. Entrada gratuita hasta completar aforo. Nos vemos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Hace unas horas he conversado por tel\u00e9fono con Pedro Garc\u00eda Aguado, el &#8216;Hermano mayor&#8217; de la &#8216;tele&#8217;, que hoy d\u00eda 13 va a estar en Granada junto a Don Emilio. Ha sido un di\u00e1logo largo e interesante, pero me quedo con esta verdad que alguno dir\u00e1 que es de perogrullo, pero no por eso [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[532],"class_list":["post-2198","post","type-post","status-publish","format-standard","hentry","category-blog","tag-hermano-mayor"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-zs","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/2198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=2198"}],"version-history":[{"count":3,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/2198\/revisions"}],"predecessor-version":[{"id":2201,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/2198\/revisions\/2201"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=2198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=2198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=2198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}