{"id":2118,"date":"2012-11-16T22:31:49","date_gmt":"2012-11-16T21:31:49","guid":{"rendered":"http:\/\/www.granadablogs.com\/juezcalatayud\/?p=2118"},"modified":"2012-11-16T22:31:49","modified_gmt":"2012-11-16T21:31:49","slug":"del-a-las-diez-aqui-al-llego-a-las-dos-de-la-madrugada-porque-me-da-la-gana","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2012\/11\/del-a-las-diez-aqui-al-llego-a-las-dos-de-la-madrugada-porque-me-da-la-gana\/","title":{"rendered":"Del &#8216;a las diez aqu\u00ed&#8217; al &#8216;lleg\u00f3 a las dos de la madrugada porque me da la gana\u00bb"},"content":{"rendered":"<p>Don Emilio ha estado esta tarde en Almer\u00eda para pronunciar su charla. Los muy fans\u00a0ya conoc\u00e9is sus argumentos, pero nunca est\u00e1 de m\u00e1s escucharlos. Aqu\u00ed os dejamos la noticia. Es de Europa Press.\u00a0\u00abLos derechos y deberes de los ni\u00f1os y ni\u00f1as ha sido la tem\u00e1tica que ha centrado la charla-coloquio que ha impartido el juez de Menores de Granada Emilio Calatayud como una de las principales actividades del programa que ha organizado la Diputaci\u00f3n Provincial para conmemorar la Convenci\u00f3n Internacional de los Derechos del Ni\u00f1o, que se celebra cada 20 de noviembre.<\/p>\n<p>La diputada provincial de Bienestar Social, Igualdad y Familia, Almudena Valent\u00edn, ha destacado en la presentaci\u00f3n la carrera de este juez y ha detallado su \u00abextenso curr\u00edculum\u00bb como magistrado en el acto que ha tenido lugar en la sede de la UNED en Almer\u00eda.<\/p>\n<p>Bajo el t\u00edtulo &#8216;Los menores: derechos, s\u00ed; pero deberes, tambi\u00e9n&#8217;, Calatayud ha demostrado \u00abun profuso conocimiento de la Ley del Menor y unas ideas muy claras\u00bb. As\u00ed, ha asegurado que \u00abtodos tenemos obligaciones para garantizar estos derechos\u00bb y que \u00abla familia es la base de la sociedad\u00bb.<\/p>\n<p>Con esta \u00faltima frase, Calatayud se ha referido a que muchos de los casos que llegan al juzgado relacionados con menores pertenecen a familias \u00abcuyos progenitores tienen problemas\u00bb. \u00abSer padre es muy dif\u00edcil. Hemos pasado del padre autoritario al padre colega, de &#8216;a las diez de la noche aqu\u00ed&#8217; a &#8216;al llego a las dos de la madrugada porque me da la gana'\u00bb, ha dicho\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Don Emilio ha estado esta tarde en Almer\u00eda para pronunciar su charla. Los muy fans\u00a0ya conoc\u00e9is sus argumentos, pero nunca est\u00e1 de m\u00e1s escucharlos. Aqu\u00ed os dejamos la noticia. Es de Europa Press.\u00a0\u00abLos derechos y deberes de los ni\u00f1os y ni\u00f1as ha sido la tem\u00e1tica que ha centrado la charla-coloquio que ha impartido el juez [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[510,511],"class_list":["post-2118","post","type-post","status-publish","format-standard","hentry","category-blog","tag-almeria","tag-conferencia"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-ya","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/2118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=2118"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/2118\/revisions"}],"predecessor-version":[{"id":2120,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/2118\/revisions\/2120"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=2118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=2118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=2118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}