{"id":20947,"date":"2025-03-27T20:59:15","date_gmt":"2025-03-27T18:59:15","guid":{"rendered":"https:\/\/www.granadablogs.com\/juezcalatayud\/?p=20947"},"modified":"2025-03-27T20:59:15","modified_gmt":"2025-03-27T18:59:15","slug":"la-serie-adolescencia-lo-que-cuenta-lo-he-vivido-como-juez-de-menores-y-cosas-peores","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2025\/03\/la-serie-adolescencia-lo-que-cuenta-lo-he-vivido-como-juez-de-menores-y-cosas-peores\/","title":{"rendered":"La serie &#8216;Adolescencia&#8217;, lo que cuenta lo he vivido como juez de Menores y cosas peores"},"content":{"rendered":"\n<p>Buenas, soy Emilio Calatayud. Por principios, no tengo televisi\u00f3n de pago, pero me las he arreglado para ver la serie  &#8216;Adolescencia&#8217;, esa de la que habla todo el mundo y que aborda un caso de asesinato entre ni\u00f1os. Lo que cuenta &#8216;Adolescencia&#8217; lo he vivido como juez de Menores y cosas peores. La serie est\u00e1 bien. Refleja de una forma muy cercana a la realidad c\u00f3mo es el caldo de cultivo de la delincuencia infantil y juvenil en la actualidad, as\u00ed como el drama que viven los padres del protagonista. Personalmente, es lo que m\u00e1s me interesa. <\/p>\n\n\n\n<p>Y una puntualizaci\u00f3n, el ni\u00f1o tiene trece a\u00f1os, as\u00ed que en Espa\u00f1a ser\u00eda inimputable. Aqu\u00ed la edad penal empieza a partir de los catorce a\u00f1os. <\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buenas, soy Emilio Calatayud. Por principios, no tengo televisi\u00f3n de pago, pero me las he arreglado para ver la serie &#8216;Adolescencia&#8217;, esa de la que habla todo el mundo y que aborda un caso de asesinato entre ni\u00f1os. Lo que cuenta &#8216;Adolescencia&#8217; lo he vivido como juez de Menores y cosas peores. La serie est\u00e1 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18131,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[],"tags":[1748,1,1461],"class_list":["post-20947","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-adolescencia","tag-blog","tag-serie"],"jetpack_featured_media_url":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2023\/07\/Juez-calatayud-Alfredo-Aguilar.jpg","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-5rR","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/20947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=20947"}],"version-history":[{"count":4,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/20947\/revisions"}],"predecessor-version":[{"id":20951,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/20947\/revisions\/20951"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media\/18131"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=20947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=20947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=20947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}