{"id":2089,"date":"2012-10-30T22:03:28","date_gmt":"2012-10-30T21:03:28","guid":{"rendered":"http:\/\/www.granadablogs.com\/juezcalatayud\/?p=2089"},"modified":"2012-10-30T22:03:28","modified_gmt":"2012-10-30T21:03:28","slug":"la-mitad-de-los-menores-denunciados-por-violencia-familiar-consumen-porros-y-alcohol","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2012\/10\/la-mitad-de-los-menores-denunciados-por-violencia-familiar-consumen-porros-y-alcohol\/","title":{"rendered":"La mitad de los menores denunciados por violencia familiar consumen porros y alcohol"},"content":{"rendered":"<p>Durante estos d\u00edas, se est\u00e1 celebrando en Valladolid un encuentro de jueces de Menores de toda Espa\u00f1a, en el que, l\u00f3gicamente, participa don Emilio. El problema de los menores que agreden a sus padres es, quiz\u00e1, el que m\u00e1s est\u00e1n dando que hablar. Aqu\u00ed os dejamos lo que ha ocurrido hoy. La informaci\u00f3n es de M. J. Pascual, del diario Norte de Castilla de Valladolid. Esperamos que os resulte interesante y ya escribiremos m\u00e1s sobre este encuentro.<\/p>\n<p>\u00abLos menores que muestran conductas agresivas en su hogar porque no reconocen el principio de autoridad, ni en casa ni en el centro escolar, no proceden exclusivamente de familias desestructuradas. Cada vez m\u00e1s, seg\u00fan pusieron ayer de manifiesto jueces y fiscales especializados, llegan a los juzgados expedientes de adolescentes de familias \u00abaparentemente normales\u00bb. Tres de cada diez menores que agreden a sus padres vienen de familias corrientes, indic\u00f3 el fiscal de Menores de Valladolid, Juan Ignacio Hern\u00e1ndez Mu\u00f1oz, quien subray\u00f3 la escalada de este tipo de delitos que se ha detectado desde 2007, vinculados tambi\u00e9n a la crisis y al aumento de las rupturas matrimoniales.<\/p>\n<div>El 70% de los menores que delinquen, apunt\u00f3 el fiscal, son inmunes al principio de autoridad y se creen iguales a sus padres. \u00abLos episodios de amenazas y violencia son formas de mostrar su voluntad de querer ser iguales a los padres\u00bb, declar\u00f3 Hern\u00e1ndez. Los asistentes a las jornadas, organizadas en Valladolid por el Consejo General del Poder Judicial (CGPJ) se mostraron de acuerdo en que es fundamental recuperar el principio de autoridad de padres y profesores para atajar el problema.<\/div>\n<div>Otra de las preocupaciones que qued\u00f3 patente en en la mesa redonda sobre los malos tratos en el \u00e1mbito familiar es el incremento del consumo de drogas entre los adolescentes, que no ven la marihuana y el cannabis como drogas con efectos tan perversos como la coca\u00edna o la hero\u00edna.<\/div>\n<div>Los porros, subrayaron, est\u00e1n detr\u00e1s de la mitad de los casos de episodios de violencia de menores que pertenecen a familias estables, y la mayor\u00eda de las veces asociado al consumo de alcohol en el tiempo de ocio, como constataron la magistrada decana Blanca Subi\u00f1as, de Burgos, y Concepci\u00f3n Rodr\u00edguez, magistrada de Menores de Madrid.<\/div>\n<div>Adem\u00e1s, los magistrados tambi\u00e9n reclamaron medidas y filtros para que la denuncia no implique la apertura de un proceso judicial. \u00abCuando un padre denuncia significa que ya ha tirado la toalla. Previamente ya han existido episodios de violencia y se siente impotente y dimite como gestor de las normas de sus hijos para que sea el juez el que decida\u00bb, resumi\u00f3 Hern\u00e1ndez\u00bb.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Durante estos d\u00edas, se est\u00e1 celebrando en Valladolid un encuentro de jueces de Menores de toda Espa\u00f1a, en el que, l\u00f3gicamente, participa don Emilio. El problema de los menores que agreden a sus padres es, quiz\u00e1, el que m\u00e1s est\u00e1n dando que hablar. Aqu\u00ed os dejamos lo que ha ocurrido hoy. La informaci\u00f3n es de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[502,58,501],"class_list":["post-2089","post","type-post","status-publish","format-standard","hentry","category-blog","tag-encuentro","tag-jueces","tag-valladolid"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-xH","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/2089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=2089"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/2089\/revisions"}],"predecessor-version":[{"id":2091,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/2089\/revisions\/2091"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=2089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=2089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=2089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}