{"id":2069,"date":"2012-10-19T20:45:04","date_gmt":"2012-10-19T19:45:04","guid":{"rendered":"http:\/\/www.granadablogs.com\/juezcalatayud\/?p=2069"},"modified":"2012-10-19T20:45:04","modified_gmt":"2012-10-19T19:45:04","slug":"cuatro-anos-de-acoso","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2012\/10\/cuatro-anos-de-acoso\/","title":{"rendered":"Cuatro a\u00f1os de acoso"},"content":{"rendered":"<div>Aqu\u00ed os dejamos una noticia de la que hoy se ha hablado mucho. La verdad es que resulta incre\u00edble que una situaci\u00f3n de este tipo se prolongue durante tanto tiempo.\u00a0Han -hemos-\u00a0fallado todos. La noticia es de Efe. \u00abLa Guardia Civil ha detenido a dos menores de la provincia de Huelva acusadas de acosar durante cuatro a\u00f1os a una compa\u00f1era del instituto en el que las tres estudian. La Guardia Civil ha indicado que las dos detenidas han sido acusadas de \u00abtrato degradante y malos tratos ps\u00edquicos\u00bb a su compa\u00f1era, que el pasado 1 de octubre interpuso una denuncia, asegurando que sufr\u00eda \u00abacoso constante, humillaciones y trato vejatorio\u00bb, como adelanta la edici\u00f3n de hoy del diario Huelva Informaci\u00f3n.<\/div>\n<div>El pasado martes las diligencias previas concluyeron con la detenci\u00f3n de las dos menores, de unos 15 a\u00f1os, que declararon en presencia de sus tutores legales durante dos horas y media, y fueron puestas en libertad con cargos, aplic\u00e1ndoles la Ley del Menor. Las dos menores, seg\u00fan las fuentes consultadas, fueron advertidas en varias ocasiones de que cesasen en su actitud, sobre todo despu\u00e9s de que se comunicasen los hechos al centro educativo, sin que se lograse que cambiasen su forma de tratar a la compa\u00f1era siguiendo los cauces normales del instituto\u00bb.<\/div>\n<div>\u00a0<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Aqu\u00ed os dejamos una noticia de la que hoy se ha hablado mucho. La verdad es que resulta incre\u00edble que una situaci\u00f3n de este tipo se prolongue durante tanto tiempo.\u00a0Han -hemos-\u00a0fallado todos. La noticia es de Efe. \u00abLa Guardia Civil ha detenido a dos menores de la provincia de Huelva acusadas de acosar durante cuatro [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[97,494],"class_list":["post-2069","post","type-post","status-publish","format-standard","hentry","category-blog","tag-acoso","tag-cuatro-anos"],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-xn","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/2069","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=2069"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/2069\/revisions"}],"predecessor-version":[{"id":2071,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/2069\/revisions\/2071"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=2069"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=2069"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=2069"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}