{"id":19279,"date":"2024-03-20T21:56:33","date_gmt":"2024-03-20T19:56:33","guid":{"rendered":"https:\/\/www.granadablogs.com\/juezcalatayud\/?p=19279"},"modified":"2024-03-20T23:15:14","modified_gmt":"2024-03-20T21:15:14","slug":"menos-mal-que-los-debates-en-el-congreso-y-el-senado-no-se-celebren-en-horario-infantil","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/juezcalatayud\/2024\/03\/menos-mal-que-los-debates-en-el-congreso-y-el-senado-no-se-celebren-en-horario-infantil\/","title":{"rendered":"Menos mal que los debates en el Congreso y el Senado no se celebran en horario infantil"},"content":{"rendered":"<p>Buenas, soy Emilio Calatayud. Como abuelo preocupado, ciudadano y juez de Menores, me alegro de que los debates en el Congreso y en el Senado no se celebren en horario infantil. Las sesiones parlamentarias se han convertido en campeonatos de lucha extrema como los que ponen a altas horas de la noche en alg\u00fan canal de televisi\u00f3n.\u00a0 Y no creo que ese nivel de agresividad sea bueno para los cerebros de los ni\u00f1os.<\/p>\n<p>Si quer\u00e9is suscribiros al blog de don Emilio lo pod\u00e9is hacer en la direcci\u00f3n que va ah\u00ed abajo y sus comentarios os llegar\u00e1n directamente, sin que la red social intermedie.<\/p>\n<p><a href=\"https:\/\/www.granadablogs.com\/juezcalatayud\/2024\/03\/hay-chavales-que-solo-se-quieren-a-si-mismos-y-otros-que-no-se-quieren-nada-y-buscan-el-carino-en-las-redes\/?fbclid=IwAR2wwxCEIsrYcv2cQs0G6B8JQUHbFsVNU97_BWfeQFQM2IK0O95XwCD6Ro8#suscribete\">Haz clic aqu\u00ed y rellena el campo con tu email<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buenas, soy Emilio Calatayud. Como abuelo preocupado, ciudadano y juez de Menores, me alegro de que los debates en el Congreso y en el Senado no se celebren en horario infantil. Las sesiones parlamentarias se han convertido en campeonatos de lucha extrema como los que ponen a altas horas de la noche en alg\u00fan canal [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10129,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[],"tags":[850,2380,3675],"class_list":["post-19279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","tag-congreso","tag-debates","tag-horario-infantil"],"jetpack_featured_media_url":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-content\/uploads\/2019\/02\/Emil.jpg","jetpack_shortlink":"https:\/\/wp.me\/p5fzW5-50X","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/19279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/comments?post=19279"}],"version-history":[{"count":7,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/19279\/revisions"}],"predecessor-version":[{"id":19287,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/posts\/19279\/revisions\/19287"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media\/10129"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/media?parent=19279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/categories?post=19279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/juezcalatayud\/wp-json\/wp\/v2\/tags?post=19279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}